{"id":10582,"date":"2017-01-24T10:48:35","date_gmt":"2017-01-24T08:48:35","guid":{"rendered":"http:\/\/aachen-shopping.de\/en\/2017\/01\/24\/exklusive-kaffeeroesterei\/"},"modified":"2017-01-24T10:53:32","modified_gmt":"2017-01-24T08:53:32","slug":"exklusive-kaffeeroesterei","status":"publish","type":"post","link":"https:\/\/aachen-shopping.de\/en\/2017\/01\/24\/exklusive-kaffeeroesterei\/","title":{"rendered":"Exklusive Kaffeer\u00f6sterei"},"content":{"rendered":"<hr \/>\n<p><span style=\"font-size: 12pt; line-height: 1.5em;\">Kaffeeliebhaber aufgepasst: Bei \u201eContigo\u201c findet am Samstag, den 28. Januar, ein Kaffeeseminar mit R\u00f6stung und Verkostung statt \u2013 also schnell noch anmelden.<\/span><\/p>\n<hr \/>\n<p><span style=\"font-size: 10pt; line-height: 1.5em;\">Bei einem Spaziergang durch die Kr\u00e4merstra\u00dfe lockt der leckere Duft von frischem Kaffee schnell in den Fairtrade-Shop \u201eContigo\u201c: Hier werden Fairtrade-Bohnen aus acht Ursprungsl\u00e4ndern im Untergeschoss traditionell trommelger\u00f6stet.<\/span><\/p>\n<p><span style=\"font-size: 10pt; line-height: 1.5em;\">Als Kaffeer\u00f6sterei ist \u201eContigo\u201c den meisten Aachenern ein Begriff, denn hier werden mehr als ein Dutzend verschiedener Bio-Kaffees angeboten, mit dabei zum Beispiel Bohnen aus Tansania, \u00c4thiopien, Brasilien oder Bolivien. Und auch die exklusive \u201eAachener Altstadtr\u00f6stung\u201c \u00fcberzeugt durch feine Aromen und nachhaltige Herstellung. Neben Kaffee wird bei \u201eContigo\u201c, als einen der gr\u00f6\u00dften Fairhandels-Importeure Deutschlands, aber auch eine gro\u00dfe Auswahl an Lederwaren, Schmuck und Geschenk-Artikeln angeboten.<\/span><\/p>\n<p><span style=\"font-size: 10pt; line-height: 1.5em;\">Interessierte k\u00f6nnen am Samstag, den 28. Januar, mit allen Sinnen in die Welt des Kaffees eintauchen: Zusammen mit dem Helene-Weber-Haus veranstaltet \u201eContigo\u201c eine Exkursion mit R\u00f6stung und Kaffeeverkostung. W\u00e4hrend der Veranstaltung erfahren die Teilnehmer auch etwas \u00fcber die Entwicklung des Kaffees von der \u00e4thiopischen Waldpflanze zum zweitwichtigsten Handelsgut der Welt. Bei der Kaffeeverkostung werden die Geschmacksnerven angesprochen, wenn die Teilnehmer die Besonderheiten unterschiedlicher Kaffee-Provenienzen entdecken.<\/span><\/p>\n<hr \/>\n<p><strong><span style=\"font-size: 10pt; line-height: 1.5em;\">Alle Interessierten k\u00f6nnen sich f\u00fcr die Veranstaltung \u201eInteressiert Sie die Bohne?\u201c am Samstag, den 28. Januar 2017, von 19.30-21 Uhr \u00fcber das Helene-Weber-Haus unter <a href=\"http:\/\/www.heleneweberhaus.de\" target=\"_blank\">www.heleneweberhaus.de <\/a>oder telefonisch unter +49-(0)241-18916359 anmelden.<\/span><\/strong><\/p>\n<hr \/>\n<p><span style=\"font-size: 10pt; line-height: 1.5em;\">Mehr zu <a href=\"https:\/\/aachen-shopping.de\/en\/genuss\/?cat_nm=Kaffee%20%26%20Tee&#038;shop_id=44448\"><strong>\u201eContigo\u201c<\/strong><\/a> in der Kr\u00e4merstra\u00dfe 20-34 gibt\u2019s unter <a href=\"http:\/\/www.aachen.contigo.de\" target=\"_blank\">www.aachen.contigo.de.<\/a><\/span><\/p>\n<hr \/>\n<p><span style=\"font-size: 8pt;\">(Fotos: David Hagemann; Sophia L\u00f6hrer)<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kaffeeliebhaber aufgepasst: Bei \u201eContigo\u201c findet am Samstag, den 28. Januar, ein Kaffeeseminar mit R\u00f6stung und Verkostung statt \u2013 also schnell noch anmelden.<\/p>\n","protected":false},"author":1,"featured_media":10574,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-10582","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-shopping-news-gb"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Exklusive Kaffeer\u00f6sterei - Einkaufen in Aachen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aachen-shopping.de\/en\/2017\/01\/24\/exklusive-kaffeeroesterei\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2017\\\/01\\\/24\\\/exklusive-kaffeeroesterei\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2017\\\/01\\\/24\\\/exklusive-kaffeeroesterei\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/#\\\/schema\\\/person\\\/e7e4ecf5a1b2dcc107deec3ae378ee7e\"},\"headline\":\"Exklusive Kaffeer\u00f6sterei\",\"datePublished\":\"2017-01-24T08:48:35+00:00\",\"dateModified\":\"2017-01-24T08:53:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2017\\\/01\\\/24\\\/exklusive-kaffeeroesterei\\\/\"},\"wordCount\":247,\"image\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2017\\\/01\\\/24\\\/exklusive-kaffeeroesterei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/EIA_Con.jpg\",\"articleSection\":[\"SHOPPING NEWS\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2017\\\/01\\\/24\\\/exklusive-kaffeeroesterei\\\/\",\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2017\\\/01\\\/24\\\/exklusive-kaffeeroesterei\\\/\",\"name\":\"Exklusive Kaffeer\u00f6sterei - Einkaufen in Aachen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2017\\\/01\\\/24\\\/exklusive-kaffeeroesterei\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2017\\\/01\\\/24\\\/exklusive-kaffeeroesterei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/EIA_Con.jpg\",\"datePublished\":\"2017-01-24T08:48:35+00:00\",\"dateModified\":\"2017-01-24T08:53:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/#\\\/schema\\\/person\\\/e7e4ecf5a1b2dcc107deec3ae378ee7e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2017\\\/01\\\/24\\\/exklusive-kaffeeroesterei\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2017\\\/01\\\/24\\\/exklusive-kaffeeroesterei\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2017\\\/01\\\/24\\\/exklusive-kaffeeroesterei\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/EIA_Con.jpg\",\"contentUrl\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/EIA_Con.jpg\",\"width\":447,\"height\":312},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2017\\\/01\\\/24\\\/exklusive-kaffeeroesterei\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exklusive Kaffeer\u00f6sterei\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/\",\"name\":\"Einkaufen in Aachen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/#\\\/schema\\\/person\\\/e7e4ecf5a1b2dcc107deec3ae378ee7e\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/author\\\/einkaufen-in-aachen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exklusive Kaffeer\u00f6sterei - Einkaufen in Aachen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aachen-shopping.de\/en\/2017\/01\/24\/exklusive-kaffeeroesterei\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aachen-shopping.de\/en\/2017\/01\/24\/exklusive-kaffeeroesterei\/#article","isPartOf":{"@id":"https:\/\/aachen-shopping.de\/en\/2017\/01\/24\/exklusive-kaffeeroesterei\/"},"author":{"name":"admin","@id":"https:\/\/aachen-shopping.de\/en\/#\/schema\/person\/e7e4ecf5a1b2dcc107deec3ae378ee7e"},"headline":"Exklusive Kaffeer\u00f6sterei","datePublished":"2017-01-24T08:48:35+00:00","dateModified":"2017-01-24T08:53:32+00:00","mainEntityOfPage":{"@id":"https:\/\/aachen-shopping.de\/en\/2017\/01\/24\/exklusive-kaffeeroesterei\/"},"wordCount":247,"image":{"@id":"https:\/\/aachen-shopping.de\/en\/2017\/01\/24\/exklusive-kaffeeroesterei\/#primaryimage"},"thumbnailUrl":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2017\/01\/EIA_Con.jpg","articleSection":["SHOPPING NEWS"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/aachen-shopping.de\/en\/2017\/01\/24\/exklusive-kaffeeroesterei\/","url":"https:\/\/aachen-shopping.de\/en\/2017\/01\/24\/exklusive-kaffeeroesterei\/","name":"Exklusive Kaffeer\u00f6sterei - Einkaufen in Aachen","isPartOf":{"@id":"https:\/\/aachen-shopping.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aachen-shopping.de\/en\/2017\/01\/24\/exklusive-kaffeeroesterei\/#primaryimage"},"image":{"@id":"https:\/\/aachen-shopping.de\/en\/2017\/01\/24\/exklusive-kaffeeroesterei\/#primaryimage"},"thumbnailUrl":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2017\/01\/EIA_Con.jpg","datePublished":"2017-01-24T08:48:35+00:00","dateModified":"2017-01-24T08:53:32+00:00","author":{"@id":"https:\/\/aachen-shopping.de\/en\/#\/schema\/person\/e7e4ecf5a1b2dcc107deec3ae378ee7e"},"breadcrumb":{"@id":"https:\/\/aachen-shopping.de\/en\/2017\/01\/24\/exklusive-kaffeeroesterei\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aachen-shopping.de\/en\/2017\/01\/24\/exklusive-kaffeeroesterei\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aachen-shopping.de\/en\/2017\/01\/24\/exklusive-kaffeeroesterei\/#primaryimage","url":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2017\/01\/EIA_Con.jpg","contentUrl":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2017\/01\/EIA_Con.jpg","width":447,"height":312},{"@type":"BreadcrumbList","@id":"https:\/\/aachen-shopping.de\/en\/2017\/01\/24\/exklusive-kaffeeroesterei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aachen-shopping.de\/en\/"},{"@type":"ListItem","position":2,"name":"Exklusive Kaffeer\u00f6sterei"}]},{"@type":"WebSite","@id":"https:\/\/aachen-shopping.de\/en\/#website","url":"https:\/\/aachen-shopping.de\/en\/","name":"Einkaufen in Aachen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aachen-shopping.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/aachen-shopping.de\/en\/#\/schema\/person\/e7e4ecf5a1b2dcc107deec3ae378ee7e","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/aachen-shopping.de\/en\/author\/einkaufen-in-aachen\/"}]}},"_links":{"self":[{"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/posts\/10582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/comments?post=10582"}],"version-history":[{"count":0,"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/posts\/10582\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/media\/10574"}],"wp:attachment":[{"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/media?parent=10582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/categories?post=10582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/tags?post=10582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}