{"id":21853,"date":"2019-11-27T12:48:07","date_gmt":"2019-11-27T11:48:07","guid":{"rendered":"https:\/\/aachen-shopping.de\/2019\/11\/27\/24-tannenbaeume-fuer-aachen\/"},"modified":"2019-11-27T13:02:26","modified_gmt":"2019-11-27T12:02:26","slug":"24-tannenbaeume-fuer-aachen","status":"publish","type":"post","link":"https:\/\/aachen-shopping.de\/en\/2019\/11\/27\/24-tannenbaeume-fuer-aachen\/","title":{"rendered":"24 Tannenb\u00e4ume f\u00fcr Aachen"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br><strong>Die Goldschmiede F\u00f6rster startet in diesem Jahr eine au\u00dfergew\u00f6hnliche und nachhaltige Adventsaktion: 24 Tannenb\u00e4ume f\u00fcr Aachen.<\/strong><br><br>Ab dem 1. Dezember werden Tag f\u00fcr Tag Paten f\u00fcr einen der 24 Tannenb\u00e4ume im Schaufenster der Goldschmiede gesucht. So sollen die B\u00e4ume einen neuen Platz finden und f\u00fcr bessere Luft und eine sch\u00f6nere Umwelt sorgen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Weitere Infos unter: <br><a rel=\"noreferrer noopener\" aria-label=\"www.goldschmiede-foerster.de (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/www.goldschmiede-foerster.de\/24-tannenbaeume-fuer-aachen\/\" target=\"_blank\"><strong>www.goldschmiede-foerster.de<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>24 Tannenb\u00e4ume f\u00fcr Aachen bei Goldschmiede F\u00f6rster<\/p>\n","protected":false},"author":1,"featured_media":21833,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-21853","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fundstuecke-gb"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>24 Tannenb\u00e4ume f\u00fcr Aachen - Einkaufen in Aachen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aachen-shopping.de\/en\/2019\/11\/27\/24-tannenbaeume-fuer-aachen\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2019\\\/11\\\/27\\\/24-tannenbaeume-fuer-aachen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2019\\\/11\\\/27\\\/24-tannenbaeume-fuer-aachen\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/#\\\/schema\\\/person\\\/e7e4ecf5a1b2dcc107deec3ae378ee7e\"},\"headline\":\"24 Tannenb\u00e4ume f\u00fcr Aachen\",\"datePublished\":\"2019-11-27T11:48:07+00:00\",\"dateModified\":\"2019-11-27T12:02:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2019\\\/11\\\/27\\\/24-tannenbaeume-fuer-aachen\\\/\"},\"wordCount\":71,\"image\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2019\\\/11\\\/27\\\/24-tannenbaeume-fuer-aachen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/EIA_SF.jpg\",\"articleSection\":[\"FIND OF THE WEEK\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2019\\\/11\\\/27\\\/24-tannenbaeume-fuer-aachen\\\/\",\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2019\\\/11\\\/27\\\/24-tannenbaeume-fuer-aachen\\\/\",\"name\":\"24 Tannenb\u00e4ume f\u00fcr Aachen - Einkaufen in Aachen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2019\\\/11\\\/27\\\/24-tannenbaeume-fuer-aachen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2019\\\/11\\\/27\\\/24-tannenbaeume-fuer-aachen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/EIA_SF.jpg\",\"datePublished\":\"2019-11-27T11:48:07+00:00\",\"dateModified\":\"2019-11-27T12:02:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/#\\\/schema\\\/person\\\/e7e4ecf5a1b2dcc107deec3ae378ee7e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2019\\\/11\\\/27\\\/24-tannenbaeume-fuer-aachen\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2019\\\/11\\\/27\\\/24-tannenbaeume-fuer-aachen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2019\\\/11\\\/27\\\/24-tannenbaeume-fuer-aachen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/EIA_SF.jpg\",\"contentUrl\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/EIA_SF.jpg\",\"width\":237,\"height\":276},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2019\\\/11\\\/27\\\/24-tannenbaeume-fuer-aachen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"24 Tannenb\u00e4ume f\u00fcr Aachen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/\",\"name\":\"Einkaufen in Aachen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/#\\\/schema\\\/person\\\/e7e4ecf5a1b2dcc107deec3ae378ee7e\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/author\\\/einkaufen-in-aachen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"24 Tannenb\u00e4ume f\u00fcr Aachen - Einkaufen in Aachen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aachen-shopping.de\/en\/2019\/11\/27\/24-tannenbaeume-fuer-aachen\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aachen-shopping.de\/en\/2019\/11\/27\/24-tannenbaeume-fuer-aachen\/#article","isPartOf":{"@id":"https:\/\/aachen-shopping.de\/en\/2019\/11\/27\/24-tannenbaeume-fuer-aachen\/"},"author":{"name":"admin","@id":"https:\/\/aachen-shopping.de\/en\/#\/schema\/person\/e7e4ecf5a1b2dcc107deec3ae378ee7e"},"headline":"24 Tannenb\u00e4ume f\u00fcr Aachen","datePublished":"2019-11-27T11:48:07+00:00","dateModified":"2019-11-27T12:02:26+00:00","mainEntityOfPage":{"@id":"https:\/\/aachen-shopping.de\/en\/2019\/11\/27\/24-tannenbaeume-fuer-aachen\/"},"wordCount":71,"image":{"@id":"https:\/\/aachen-shopping.de\/en\/2019\/11\/27\/24-tannenbaeume-fuer-aachen\/#primaryimage"},"thumbnailUrl":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2019\/11\/EIA_SF.jpg","articleSection":["FIND OF THE WEEK"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/aachen-shopping.de\/en\/2019\/11\/27\/24-tannenbaeume-fuer-aachen\/","url":"https:\/\/aachen-shopping.de\/en\/2019\/11\/27\/24-tannenbaeume-fuer-aachen\/","name":"24 Tannenb\u00e4ume f\u00fcr Aachen - Einkaufen in Aachen","isPartOf":{"@id":"https:\/\/aachen-shopping.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aachen-shopping.de\/en\/2019\/11\/27\/24-tannenbaeume-fuer-aachen\/#primaryimage"},"image":{"@id":"https:\/\/aachen-shopping.de\/en\/2019\/11\/27\/24-tannenbaeume-fuer-aachen\/#primaryimage"},"thumbnailUrl":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2019\/11\/EIA_SF.jpg","datePublished":"2019-11-27T11:48:07+00:00","dateModified":"2019-11-27T12:02:26+00:00","author":{"@id":"https:\/\/aachen-shopping.de\/en\/#\/schema\/person\/e7e4ecf5a1b2dcc107deec3ae378ee7e"},"breadcrumb":{"@id":"https:\/\/aachen-shopping.de\/en\/2019\/11\/27\/24-tannenbaeume-fuer-aachen\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aachen-shopping.de\/en\/2019\/11\/27\/24-tannenbaeume-fuer-aachen\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aachen-shopping.de\/en\/2019\/11\/27\/24-tannenbaeume-fuer-aachen\/#primaryimage","url":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2019\/11\/EIA_SF.jpg","contentUrl":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2019\/11\/EIA_SF.jpg","width":237,"height":276},{"@type":"BreadcrumbList","@id":"https:\/\/aachen-shopping.de\/en\/2019\/11\/27\/24-tannenbaeume-fuer-aachen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aachen-shopping.de\/en\/"},{"@type":"ListItem","position":2,"name":"24 Tannenb\u00e4ume f\u00fcr Aachen"}]},{"@type":"WebSite","@id":"https:\/\/aachen-shopping.de\/en\/#website","url":"https:\/\/aachen-shopping.de\/en\/","name":"Einkaufen in Aachen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aachen-shopping.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/aachen-shopping.de\/en\/#\/schema\/person\/e7e4ecf5a1b2dcc107deec3ae378ee7e","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/aachen-shopping.de\/en\/author\/einkaufen-in-aachen\/"}]}},"_links":{"self":[{"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/posts\/21853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/comments?post=21853"}],"version-history":[{"count":0,"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/posts\/21853\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/media\/21833"}],"wp:attachment":[{"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/media?parent=21853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/categories?post=21853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/tags?post=21853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}