{"id":22422,"date":"2020-02-10T12:43:38","date_gmt":"2020-02-10T11:43:38","guid":{"rendered":"https:\/\/aachen-shopping.de\/2020\/02\/10\/kraeuterdrogerie-victor\/"},"modified":"2020-02-11T09:48:51","modified_gmt":"2020-02-11T08:48:51","slug":"kraeuterdrogerie-victor","status":"publish","type":"post","link":"https:\/\/aachen-shopping.de\/en\/2020\/02\/10\/kraeuterdrogerie-victor\/","title":{"rendered":"Kr\u00e4uter&shy;droge&shy;rie Victor"},"content":{"rendered":"\n<p><strong>Besonders lustig findet es Michaela Victor, wenn Kunden bei ihrem ersten Besuch sagen: \u201eSie sind aber noch nicht lange hier, oder? Haben Sie auch Tee?\u201c. Denn die Kr\u00e4uterdrogerie Victor in der Jakobstra\u00dfe gibt es seit fast 130 Jahren und ja, es gibt hier jeden Tee au\u00dfer schwarzen.<\/strong><\/p>\n\n\n\n<p>Im Jahr 1892 machte sich Ludwig Victor mit einem Gesch\u00e4ft selbstst\u00e4ndig, in dem es \u201eKolonial-Material\u201c, Su\u0308dfru\u0308chte, Weine, Drogeriewaren und Cigarren gab, nach dem Zweiten Weltkrieg wurde daraus dann die Victoria-Drogerie. Michaela Victors Mutter \u00fcbernahm das Gesch\u00e4ft 1972 von ihrem Vater, baute es komplett um und erweiterte das Sortiment um Reformhauswaren, Heilkr\u00e4uter, selbstgemachte Kosmetik, Genusstees und Artikel zur Weinherstellung. Michaela Victor wuchs quasi in dem Gesch\u00e4ft auf: \u201eDer Laden war gleichzeitig Wohnzimmer und Kinderstube f\u00fcr mich\u201c, erinnert sie sich.<br>\nNach Abitur, Drogistenlehre und BWL-Studium \u00fcbernahm sie dann 1999 das Gesch\u00e4ft mit dem Vorsatz: \u201eIch mach\u2018s besser.\u201c Zuerst einmal verabschiedete sie sich von dem orange-gr\u00fcnen 70er Jahre-Stil, strich die W\u00e4nde in warmem Rot und machte das Gesch\u00e4ft zu einer Kr\u00e4uterdrogerie im wahrsten Sinne des Wortes: Heute gibt es hier \u00fcber 300 Heilkr\u00e4uter, selbstkomponierte Genu\u00dftees, Gew\u00fcrzmischungen und Heiltees. Auch  ayurvedische Zahncremes, K\u00f6rperspray aus naturreinen \u00e4therischen \u00d6len, verschiedene Heilerden und alternative S\u00fc\u00dfungsmittel gibt\u2018s hier, au\u00dferdem finden Hobby-Winzer alles zur Weinherstellung, von der Hefe bis zum G\u00e4rbeh\u00e4lter. <\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u201eWir sind ein Frauenladen\u201c \u2026<\/strong><\/h4>\n\n\n\n<p>\u2026<strong> sagt Michaela Victor lachend. <\/strong>Sie hat sechs hoch qualifizierte Mitarbeiterinnen, meist Quereinsteigerinnen aus anderen Berufen wir etwa Floristin, Aromatherapeutin oder Hebamme, denn ein Schwerpunkt liegt auf der kompetenten Beratung der Kundinnen. Zwar kommen \u00fcberwiegend Frauen, aber inzwischen auch immer mehr M\u00e4nner, meist j\u00fcngere. <br> \u201eIch darf keine Heilversprechen machen, weil ich keine \u00c4rztin bin\u201c, erkl\u00e4rt die Drogistin, aber sie kann von den Erfahrungen anderer Kunden berichten, au\u00dferdem probiert sie alle Mittel selber an sich aus. \u201eIch brauche keinen Arzt und keine Apotheke\u201c, sagt sie, nur hom\u00f6opathische Mittel kauft sie gelegentlich, denn die d\u00fcrfen nur in Apotheken gef\u00fchrt werden.<br> Fr\u00fcher stellten sie und ihre Mitarbeiterinnen auch Kosmetik selbst her, doch neue EU-Richtlinien machten die Zulassung zu aufw\u00e4ndig, deshalb hat sie nun Produkte von  ausgesuchten Naturkosmetikherstellern im Sortiment, zum Beispiel Bio-Kosmetik von Weleda oder Cremes und Salben aus der Allg\u00e4uer Bahnhof Apotheke und regional aus L\u00fcttich die Firma Floressence. Tees, \u00e4therische \u00d6le und Kr\u00e4utermischungen werden aber selbst hergestellt, der ganze Laden riecht k\u00f6stlich nach Kr\u00e4utern.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Kompetente Beratung, neue Therapieformen und kein Verpackungsm\u00fcll<\/strong><\/h4>\n\n\n\n<p> Immer mehr Menschen vertrauen lieber auf die die Heilkr\u00e4fte der Natur als auf die Pharmaindustrie, die Schwerpunkte der Beratung liegen auf Verdauung, Schwangerschaft, Wechseljahrsbeschwerden, Gelenkproblemen und in der kalten Jahreszeit nat\u00fcrlich Erk\u00e4ltungen. Wie \u00fcberall gibt es auch auf dem Gebiet Gesundheit und Wellness Trends, zur Zeit sind Kurkuma und Hagebuttenpulver sehr gefragt, die schmerzlindernd und entz\u00fcndungshemmend wirken sollen. Eher \u00fcbersch\u00e4tzt hingegen wird laut Michaela Victor die Modepflanze Ashwagandha, der \u201eindische Ginseng\u201c.<br> Durch ihr Interesse an Themen wie Naturheilkunde, Gesunderhaltung, Heilkr\u00e4uter und deren Anwendungen erweitern auch immer wieder neue Therapieformen wie Aromatherapie, Hildegardmedizin oder Gemmotherapie \u2013 die Behandlung von Krankheiten mit Ausz\u00fcgen aus frischen Knospen, Triebsprossen und Wurzelspitzen \u2013 das Sortiment. \u00dcber den unverpackt-Trend hingegen kann Michaela Victor nur lachen: \u201eDa waren wir der Zeit voraus, bei uns kann man sich die Ware schon immer lose abf\u00fcllen und wieder auff\u00fcllen lassen.\u201c<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p class=\"has-small-font-size\">(Fotos: Einkaufen in Aachen\/Marie-Luise Manthei)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Kr\u00e4uterdrogerie Victor in der Jakobstra\u00dfe gibt es seit fast 130 Jahren und ja, es gibt hier jeden Tee \u2013 au\u00dfer schwarzen.<\/p>\n","protected":false},"author":1,"featured_media":22443,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-22422","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-shopping-news-gb"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kr\u00e4uter&shy;droge&shy;rie Victor - Einkaufen in Aachen<\/title>\n<meta name=\"description\" content=\"Alles f\u00fcr die Gesundheit: Heilkr\u00e4uter, Gew\u00fcrze, Bachbl\u00fcten, Naturheilmittel sowie Artikel zur Weinherstellung, Kosmetikprodukte, \u00d6le, individuelle Teekreationen und Kosmetikserien werden angeboten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aachen-shopping.de\/en\/2020\/02\/10\/kraeuterdrogerie-victor\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2020\\\/02\\\/10\\\/kraeuterdrogerie-victor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2020\\\/02\\\/10\\\/kraeuterdrogerie-victor\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/#\\\/schema\\\/person\\\/e7e4ecf5a1b2dcc107deec3ae378ee7e\"},\"headline\":\"Kr\u00e4uter&shy;droge&shy;rie Victor\",\"datePublished\":\"2020-02-10T11:43:38+00:00\",\"dateModified\":\"2020-02-11T08:48:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2020\\\/02\\\/10\\\/kraeuterdrogerie-victor\\\/\"},\"wordCount\":578,\"image\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2020\\\/02\\\/10\\\/kraeuterdrogerie-victor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/EIA_KVb-1.jpg\",\"articleSection\":[\"SHOPPING NEWS\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2020\\\/02\\\/10\\\/kraeuterdrogerie-victor\\\/\",\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2020\\\/02\\\/10\\\/kraeuterdrogerie-victor\\\/\",\"name\":\"Kr\u00e4uter&shy;droge&shy;rie Victor - Einkaufen in Aachen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2020\\\/02\\\/10\\\/kraeuterdrogerie-victor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2020\\\/02\\\/10\\\/kraeuterdrogerie-victor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/EIA_KVb-1.jpg\",\"datePublished\":\"2020-02-10T11:43:38+00:00\",\"dateModified\":\"2020-02-11T08:48:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/#\\\/schema\\\/person\\\/e7e4ecf5a1b2dcc107deec3ae378ee7e\"},\"description\":\"Alles f\u00fcr die Gesundheit: Heilkr\u00e4uter, Gew\u00fcrze, Bachbl\u00fcten, Naturheilmittel sowie Artikel zur Weinherstellung, Kosmetikprodukte, \u00d6le, individuelle Teekreationen und Kosmetikserien werden angeboten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2020\\\/02\\\/10\\\/kraeuterdrogerie-victor\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2020\\\/02\\\/10\\\/kraeuterdrogerie-victor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2020\\\/02\\\/10\\\/kraeuterdrogerie-victor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/EIA_KVb-1.jpg\",\"contentUrl\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/EIA_KVb-1.jpg\",\"width\":430,\"height\":280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/2020\\\/02\\\/10\\\/kraeuterdrogerie-victor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kr\u00e4uter&shy;droge&shy;rie Victor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/\",\"name\":\"Einkaufen in Aachen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/#\\\/schema\\\/person\\\/e7e4ecf5a1b2dcc107deec3ae378ee7e\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/en\\\/author\\\/einkaufen-in-aachen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kr\u00e4uter&shy;droge&shy;rie Victor - Einkaufen in Aachen","description":"Alles f\u00fcr die Gesundheit: Heilkr\u00e4uter, Gew\u00fcrze, Bachbl\u00fcten, Naturheilmittel sowie Artikel zur Weinherstellung, Kosmetikprodukte, \u00d6le, individuelle Teekreationen und Kosmetikserien werden angeboten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aachen-shopping.de\/en\/2020\/02\/10\/kraeuterdrogerie-victor\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aachen-shopping.de\/en\/2020\/02\/10\/kraeuterdrogerie-victor\/#article","isPartOf":{"@id":"https:\/\/aachen-shopping.de\/en\/2020\/02\/10\/kraeuterdrogerie-victor\/"},"author":{"name":"admin","@id":"https:\/\/aachen-shopping.de\/en\/#\/schema\/person\/e7e4ecf5a1b2dcc107deec3ae378ee7e"},"headline":"Kr\u00e4uter&shy;droge&shy;rie Victor","datePublished":"2020-02-10T11:43:38+00:00","dateModified":"2020-02-11T08:48:51+00:00","mainEntityOfPage":{"@id":"https:\/\/aachen-shopping.de\/en\/2020\/02\/10\/kraeuterdrogerie-victor\/"},"wordCount":578,"image":{"@id":"https:\/\/aachen-shopping.de\/en\/2020\/02\/10\/kraeuterdrogerie-victor\/#primaryimage"},"thumbnailUrl":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2020\/02\/EIA_KVb-1.jpg","articleSection":["SHOPPING NEWS"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/aachen-shopping.de\/en\/2020\/02\/10\/kraeuterdrogerie-victor\/","url":"https:\/\/aachen-shopping.de\/en\/2020\/02\/10\/kraeuterdrogerie-victor\/","name":"Kr\u00e4uter&shy;droge&shy;rie Victor - Einkaufen in Aachen","isPartOf":{"@id":"https:\/\/aachen-shopping.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aachen-shopping.de\/en\/2020\/02\/10\/kraeuterdrogerie-victor\/#primaryimage"},"image":{"@id":"https:\/\/aachen-shopping.de\/en\/2020\/02\/10\/kraeuterdrogerie-victor\/#primaryimage"},"thumbnailUrl":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2020\/02\/EIA_KVb-1.jpg","datePublished":"2020-02-10T11:43:38+00:00","dateModified":"2020-02-11T08:48:51+00:00","author":{"@id":"https:\/\/aachen-shopping.de\/en\/#\/schema\/person\/e7e4ecf5a1b2dcc107deec3ae378ee7e"},"description":"Alles f\u00fcr die Gesundheit: Heilkr\u00e4uter, Gew\u00fcrze, Bachbl\u00fcten, Naturheilmittel sowie Artikel zur Weinherstellung, Kosmetikprodukte, \u00d6le, individuelle Teekreationen und Kosmetikserien werden angeboten.","breadcrumb":{"@id":"https:\/\/aachen-shopping.de\/en\/2020\/02\/10\/kraeuterdrogerie-victor\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aachen-shopping.de\/en\/2020\/02\/10\/kraeuterdrogerie-victor\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aachen-shopping.de\/en\/2020\/02\/10\/kraeuterdrogerie-victor\/#primaryimage","url":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2020\/02\/EIA_KVb-1.jpg","contentUrl":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2020\/02\/EIA_KVb-1.jpg","width":430,"height":280},{"@type":"BreadcrumbList","@id":"https:\/\/aachen-shopping.de\/en\/2020\/02\/10\/kraeuterdrogerie-victor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aachen-shopping.de\/en\/"},{"@type":"ListItem","position":2,"name":"Kr\u00e4uter&shy;droge&shy;rie Victor"}]},{"@type":"WebSite","@id":"https:\/\/aachen-shopping.de\/en\/#website","url":"https:\/\/aachen-shopping.de\/en\/","name":"Einkaufen in Aachen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aachen-shopping.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/aachen-shopping.de\/en\/#\/schema\/person\/e7e4ecf5a1b2dcc107deec3ae378ee7e","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/aachen-shopping.de\/en\/author\/einkaufen-in-aachen\/"}]}},"_links":{"self":[{"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/posts\/22422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/comments?post=22422"}],"version-history":[{"count":0,"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/posts\/22422\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/media\/22443"}],"wp:attachment":[{"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/media?parent=22422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/categories?post=22422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aachen-shopping.de\/en\/wp-json\/wp\/v2\/tags?post=22422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}