{"id":23048,"date":"2020-03-18T13:20:47","date_gmt":"2020-03-18T12:20:47","guid":{"rendered":"https:\/\/aachen-shopping.de\/2020\/03\/18\/adami\/"},"modified":"2020-03-18T13:20:47","modified_gmt":"2020-03-18T12:20:47","slug":"adami","status":"publish","type":"post","link":"https:\/\/aachen-shopping.de\/fr\/2020\/03\/18\/adami\/","title":{"rendered":"Adami"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br><strong><em>\u201eWer seine Stadt liebt, unterst\u00fctzt Gesch\u00e4fte mit Seele\u201c, so Asgar Adami. In seinem Modefachgesch\u00e4ft gibt es nicht nur kompetente Beratung, sondern auch pers\u00f6nliche  Gespr\u00e4che und dazu schon mal einen Espresso, Wasser oder Sekt.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asgar Adami, der in Persien geboren wurde, hat in Maastricht Mode und Kost\u00fcmdesign studiert. Im Anschluss an das Studium er\u00f6ffnete er 1981 direkt sein erstes Gesch\u00e4ft mitten im Aachener Zentrum. \u201eAkzente\u201c hie\u00df der Laden im Hof, 14 Jahre lang verkaufte er hier freche, auch punkige Mode, unter anderem von Moschino, Romeo Gigli und Jean Paul Gaultier, seinem damaligen Lieblingsdesigner.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Parallel arbeitete er auch immer als Kost\u00fcmdesigner f\u00fcr Fernsehen, Werbung und Events und entwarf eine eigene Modekollektion, viele St\u00fccke befinden sich noch in dem Atelier im Souterrain. Aus den 80er und 90er Jahren stammen die vielen Schwarzwei\u00dffotos in seinem Gesch\u00e4ft, auf denen Asgar Adami unter anderem mit Karl Lagerfeld, Catherine Deneuve oder Christopher Lambert zu sehen ist.<br><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Purismus, Qualit\u00e4t und pers\u00f6nliche Beratung<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"> Seit damals hat sich sein Stil ge\u00e4ndert: Die Atmosph\u00e4re in seinem Gesch\u00e4ft am Markt, das er zusammen mit seiner Frau f\u00fchrt, ist puristisch, schlicht und geordnet. Es \u00fcberwiegen klassische Farben wie Grau, Wei\u00df, Dunkelblau und Sand, aber man sieht auch saisonale Trendfarben, allerdings keine aufdringlichen Logos und kein Bling Bling. <br><br> \u201eWir setzen auf dezente Eleganz, die einen Hauch von Gro\u00dfstadtflair ausstrahlt, von elegant bis klassisch und von sportlich bis individuell\u201c, erkl\u00e4rt Adami das Konzept. \u201eFrauen sollen strahlen, sie sollen feminin sein, ohne sich zu verkleiden. Man kann auch sexy sein ohne zu viel Haut zu zeigen.\u201c <br><br> Besonders wichtig ist ihm und seinem Team die individuelle und ehrliche Beratung der Kundinnen, damit sie das passende Outfit f\u00fcr einen bestimmten Anlass, aber auch f\u00fcr ihre Figur finden. \u201eViele Frauen wissen selbst gar nicht, was ihnen steht, sondern laufen der aktuellen Mode oder irgendwelche Influencerinnen nach,\u201c kritisiert er, \u201evielen Social Media-Vorbildern fehlt das Feeling f\u00fcr Menschen, sowas wie unsere Beratung kann das Internet gar nicht leisten\u201c.<br><br> Seine Mitarbeiterinnen geben den Kundinnen ein offenes Feedback, raten auch mal von einem Outfit ab oder verweisen sogar auf die Konkurrenz, denn Adami und sein Team sind fest \u00fcberzeugt, dass diese Haltung sich letztendlich auszahlt \u2013 die vielen Stammkundinnen sprechen daf\u00fcr. Sie sch\u00e4tzen die schlichte Eleganz mit raffinierten Akzenten, die guten Schnitte und die hochwertigen Materialien der Kleidung. Zum Service z\u00e4hlen auch Beratungs- und Anprobetermine au\u00dferhalb der \u00d6ffnungszeiten, individuelle \u00c4nderungen im eigenen Atelier \u2013 und der ein oder andere Sekt oder Espresso.<br><br> Das Ambiente in dem hellen Ladenlokal ist angenehm schlicht, zwei Ledersessel laden zum Bl\u00e4ttern in den ausliegenden Modekatalogen und B\u00fcchern ein. Das Sortiment umfasst Marken wie Armani, Max Mara, Drykorn, Jan Mayen oder Dorothee Schumacher, aber auch die kultigen Gummistiefel von Hunter, die gerne auf Festivals getragen werden.<br><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Langlebigkeit und Zukunftspl\u00e4ne<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"> Nat\u00fcrlich liegen die Preise der bekannten internationalen Modedesigner \u00fcber denen der bekannten gro\u00dfen Modeketten, daf\u00fcr wissen Adamis Kundinnen zu sch\u00e4tzen, dass man die Sachen, die man dort kauft, lange tragen und vielfach kombinieren kann. Au\u00dferdem entsteht immer mehr Bewusstsein f\u00fcr Nachhaltigkeit, viele Mode-Firmen verarbeiten inzwischen beispielsweise statt Daunen Stoffe aus recycelten Flaschen oder verwenden andere umweltschonende Materialien.<br><br> Fragt man Asgar Adami nach der Zukunft, dann steht 2021 zuerst einmal das 40. Firmenjubil\u00e4um an \u2013 ein gro\u00dfes Event, zu dem auch seine Partnerunternehmen sich etwas Besonderes einfallen lassen werden. Und neben der Mode ist da ja auch noch das alte Stadtbad am Bl\u00fccherplatz, das er mit viel Liebe zum Detail zu einer ungew\u00f6hnlichen Eventlocation umgebaut hat, die man als Raum f\u00fcr Kunst und Kultur, Workshops, Meetings oder private Feste und Firmenfeiern buchen kann \u2013 der Mann hat eben einfach Geschmack.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">(Fotos: Einkaufen in Aachen\/Marie-Luise Manthei)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201eWer seine Stadt liebt, unterst\u00fctzt Gesch\u00e4fte mit Seele\u201c, so Asgar Adami. In seinem Modefachgesch\u00e4ft gibt es nicht nur kompetente Beratung, sondern auch pers\u00f6nliche  Gespr\u00e4che und dazu schon mal einen Espresso, Wasser oder Sekt.<\/p>\n","protected":false},"author":1,"featured_media":22654,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-23048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-shopping-news-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Adami - Einkaufen in Aachen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aachen-shopping.de\/fr\/2020\/03\/18\/adami\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2020\\\/03\\\/18\\\/adami\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2020\\\/03\\\/18\\\/adami\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/#\\\/schema\\\/person\\\/e7e4ecf5a1b2dcc107deec3ae378ee7e\"},\"headline\":\"Adami\",\"datePublished\":\"2020-03-18T12:20:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2020\\\/03\\\/18\\\/adami\\\/\"},\"wordCount\":630,\"image\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2020\\\/03\\\/18\\\/adami\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/EIA_AD_a.jpg\",\"articleSection\":[\"SHOPPING-NEWS\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2020\\\/03\\\/18\\\/adami\\\/\",\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2020\\\/03\\\/18\\\/adami\\\/\",\"name\":\"Adami - Einkaufen in Aachen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2020\\\/03\\\/18\\\/adami\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2020\\\/03\\\/18\\\/adami\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/EIA_AD_a.jpg\",\"datePublished\":\"2020-03-18T12:20:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/#\\\/schema\\\/person\\\/e7e4ecf5a1b2dcc107deec3ae378ee7e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2020\\\/03\\\/18\\\/adami\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2020\\\/03\\\/18\\\/adami\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2020\\\/03\\\/18\\\/adami\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/EIA_AD_a.jpg\",\"contentUrl\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/EIA_AD_a.jpg\",\"width\":237,\"height\":276},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2020\\\/03\\\/18\\\/adami\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adami\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/\",\"name\":\"Einkaufen in Aachen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/#\\\/schema\\\/person\\\/e7e4ecf5a1b2dcc107deec3ae378ee7e\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/author\\\/einkaufen-in-aachen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Adami - Einkaufen in Aachen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aachen-shopping.de\/fr\/2020\/03\/18\/adami\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aachen-shopping.de\/fr\/2020\/03\/18\/adami\/#article","isPartOf":{"@id":"https:\/\/aachen-shopping.de\/fr\/2020\/03\/18\/adami\/"},"author":{"name":"admin","@id":"https:\/\/aachen-shopping.de\/fr\/#\/schema\/person\/e7e4ecf5a1b2dcc107deec3ae378ee7e"},"headline":"Adami","datePublished":"2020-03-18T12:20:47+00:00","mainEntityOfPage":{"@id":"https:\/\/aachen-shopping.de\/fr\/2020\/03\/18\/adami\/"},"wordCount":630,"image":{"@id":"https:\/\/aachen-shopping.de\/fr\/2020\/03\/18\/adami\/#primaryimage"},"thumbnailUrl":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2020\/03\/EIA_AD_a.jpg","articleSection":["SHOPPING-NEWS"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/aachen-shopping.de\/fr\/2020\/03\/18\/adami\/","url":"https:\/\/aachen-shopping.de\/fr\/2020\/03\/18\/adami\/","name":"Adami - Einkaufen in Aachen","isPartOf":{"@id":"https:\/\/aachen-shopping.de\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aachen-shopping.de\/fr\/2020\/03\/18\/adami\/#primaryimage"},"image":{"@id":"https:\/\/aachen-shopping.de\/fr\/2020\/03\/18\/adami\/#primaryimage"},"thumbnailUrl":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2020\/03\/EIA_AD_a.jpg","datePublished":"2020-03-18T12:20:47+00:00","author":{"@id":"https:\/\/aachen-shopping.de\/fr\/#\/schema\/person\/e7e4ecf5a1b2dcc107deec3ae378ee7e"},"breadcrumb":{"@id":"https:\/\/aachen-shopping.de\/fr\/2020\/03\/18\/adami\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aachen-shopping.de\/fr\/2020\/03\/18\/adami\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aachen-shopping.de\/fr\/2020\/03\/18\/adami\/#primaryimage","url":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2020\/03\/EIA_AD_a.jpg","contentUrl":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2020\/03\/EIA_AD_a.jpg","width":237,"height":276},{"@type":"BreadcrumbList","@id":"https:\/\/aachen-shopping.de\/fr\/2020\/03\/18\/adami\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aachen-shopping.de\/fr\/"},{"@type":"ListItem","position":2,"name":"Adami"}]},{"@type":"WebSite","@id":"https:\/\/aachen-shopping.de\/fr\/#website","url":"https:\/\/aachen-shopping.de\/fr\/","name":"Einkaufen in Aachen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aachen-shopping.de\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/aachen-shopping.de\/fr\/#\/schema\/person\/e7e4ecf5a1b2dcc107deec3ae378ee7e","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/aachen-shopping.de\/fr\/author\/einkaufen-in-aachen\/"}]}},"_links":{"self":[{"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/posts\/23048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/comments?post=23048"}],"version-history":[{"count":0,"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/posts\/23048\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/media\/22654"}],"wp:attachment":[{"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/media?parent=23048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/categories?post=23048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/tags?post=23048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}