{"id":30158,"date":"2023-01-19T11:08:32","date_gmt":"2023-01-19T10:08:32","guid":{"rendered":"https:\/\/aachen-shopping.de\/2023\/01\/19\/galerie-am-elisengarten\/"},"modified":"2023-01-19T11:08:32","modified_gmt":"2023-01-19T10:08:32","slug":"galerie-am-elisengarten","status":"publish","type":"post","link":"https:\/\/aachen-shopping.de\/fr\/2023\/01\/19\/galerie-am-elisengarten\/","title":{"rendered":"Galerie Am Elisengarten"},"content":{"rendered":"<h2>Wo die Br\u00fcder Andreas und Klaus Petzold Kunstwerken einen Raum geben<\/h2>\n<p><strong>Andreas und Klaus Petzold haben mit ihrem Umbau im Jahre 2011 eine moderne und offenere Epoche ihrer Galerie begonnen. Hier dreht sich alles um Kunst.<\/strong><\/p>\n<p>Die Eltern gr\u00fcndeten in den 70er Jahren auf der Theaterstra\u00dfe, siedelten 1980 dann zur Hartmannstra\u00dfe. In dem herrschaftlichen Stadthaus residiert die <strong><a href=\"https:\/\/aachen-shopping.de\/fr\/geschafte-von-a-bis-z\/?sel_alphabets=G&#038;shop_id=27513\">Galerie gleich am Elisengarten<\/a><\/strong> und zieht viele Blicke auf sich. Andreas und Klaus Petzold sind in das Galerieleben und den Kunsthandel wortw\u00f6rtlich hineingewachsen. Das Elternhaus, zahlreiche Seminare bei Kunsthistorikern, Museums- und Messebesuche haben dazu gef\u00fchrt, dass Kunstinteressierte, Sammler \u2013 aber auch Kunstneulinge &#8211; in der Galerie am Elisengarten seit 42 Jahren wunderbar beraten werden. Andreas und Klaus waren in den vergangenen Jahrzehnten auf vielen Messen als Aussteller vertreten. \u201eWir geben so unsere Visitenkarte ab\u201c, erkl\u00e4rt Petzold. Denn Interessierte und Sammler kommen oft aus der Ferne.<br \/>\nEine gro\u00dfe Schaufensterfront l\u00e4sst den Blick in die Galerie wandern. Mittig ragt eine rote, drehbare, schmale Wand durch eine \u00d6ffnung nach oben und weist den Weg zur zweiten Etage der Galerie, die auch voller Kunst und Plastiken ist.<\/p>\n<p>&nbsp;<\/p>\n<h4>\u201eKunst ist Ausdruck der Zeit\u201c<\/h4>\n<p>Kunstwerke in der Galerie am Elisengarten sind Gem\u00e4lde und Plastiken aus der Zeit um 1800 bis heute. Gerhard Arnold, G\u00fcnther Becker und Joan Stephan sehen wir zum Beispiel mit einzelnen Werken. Von gro\u00dfem Interesse ist daneben die Verwaltung des Nachlass Peter Lacroix, dessen Werke vereinzelt immer wieder ausgestellt werden. Wir entdecken in den Ausstellungsr\u00e4umen Bilder von Frans van de Wal, Plastiken von Professor Wolfgang Binding und Oliver Czarnetta sowie Bilder von Karl Otto G\u00f6tz. G\u00f6tz, in Aachen geboren, war einer der bedeutendsten Maler der abstrakten Kunst und des Informel in Deutschland. Er wurde 103 Jahre alt und Andreas Petzold erz\u00e4hlt von den vielen Gespr\u00e4chen mit ihm.<br \/>\nDie \u201eoffensive Preisauszeichnung\u201c \u2013 so Andreas Petzold \u2013 aller Werke soll die Ber\u00fchrungsangst der Besucher mindern. So schufen die Galeristen in der Pandemie auch den Begriff \u201eEinsteigerkunst\u201c, Kunst f\u00fcr kleines Budget (ca. 500 Euro).<br \/>\nZus\u00e4tzlich zum Kunstsortiment glitzert und blinkt Schmuck aus Privatverk\u00e4ufen in Vitrinen. In Zusammenarbeit mit einem Goldschmiedemeister wird der Wert der Schmuckst\u00fccke ermittelt und hier zum Verkauf angeboten.<\/p>\n<p>&nbsp;<\/p>\n<h4>\u201eWir begleiten Ware, die bedeutend mehr als Ware ist\u201c, so der Galerist.<\/h4>\n<p>Mit individueller Beratung und einem umfangreichen Service schaffen die Inhaber mit ihren Mitarbeitern ein Gesamtpaket, das die Kunden gerne wiederkommen l\u00e4sst. So bieten sie zum Beispiel auch an, ein Bild zur Probeh\u00e4ngung mit nach Hause zu nehmen. \u201eVern\u00fcnftige H\u00e4ngung ist wichtig\u201c, so Andreas Petzold \u2013 sie beraten, an welchen Ort es am besten passt, bieten auch das Aufh\u00e4ngen des Bildes an. Individuelle Rahmungen, Reinigung von Bildern, Restaurationen \u2013 alles in Zusammenarbeit mit Spezialisten. Auch hier wird ganz genau auf die faire Preisgestaltung des Services geachtet.<\/p>\n<p>&nbsp;<\/p>\n<h4>\u201eKunst hat mit Emotionalit\u00e4t zu tun\u201c<\/h4>\n<p>Die Galeristen sehen sich selbst als \u201eKatalysator und Mittler\u201c. Vereinzelt haben sie beim Kauf von Kunst das Gef\u00fchl, dass K\u00fcnstler und Kunde Freunde sein k\u00f6nnten. \u201eManchmal ist hinter Kunst etwas, was Menschen verbindet. Magic. So geh\u00f6rt zu Kunst immer etwas Menschliches; man kann nichts wiegen, nichts messen.\u201c<\/p>\n<hr \/>\n<p><span style=\"font-size: 8pt;\">Fotos: Einkaufen in Aachen\/Marie Luise Manthei<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In der Galerie von Andreas und Klaus Petzold dreht sich alles um Kunst &#8230;<\/p>\n","protected":false},"author":1,"featured_media":30147,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-30158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-shopping-news-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Galerie Am Elisengarten - Einkaufen in Aachen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aachen-shopping.de\/fr\/2023\/01\/19\/galerie-am-elisengarten\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2023\\\/01\\\/19\\\/galerie-am-elisengarten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2023\\\/01\\\/19\\\/galerie-am-elisengarten\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/#\\\/schema\\\/person\\\/e7e4ecf5a1b2dcc107deec3ae378ee7e\"},\"headline\":\"Galerie Am Elisengarten\",\"datePublished\":\"2023-01-19T10:08:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2023\\\/01\\\/19\\\/galerie-am-elisengarten\\\/\"},\"wordCount\":536,\"image\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2023\\\/01\\\/19\\\/galerie-am-elisengarten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/EIA_GaEg.jpg\",\"articleSection\":[\"SHOPPING-NEWS\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2023\\\/01\\\/19\\\/galerie-am-elisengarten\\\/\",\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2023\\\/01\\\/19\\\/galerie-am-elisengarten\\\/\",\"name\":\"Galerie Am Elisengarten - Einkaufen in Aachen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2023\\\/01\\\/19\\\/galerie-am-elisengarten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2023\\\/01\\\/19\\\/galerie-am-elisengarten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/EIA_GaEg.jpg\",\"datePublished\":\"2023-01-19T10:08:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/#\\\/schema\\\/person\\\/e7e4ecf5a1b2dcc107deec3ae378ee7e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2023\\\/01\\\/19\\\/galerie-am-elisengarten\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2023\\\/01\\\/19\\\/galerie-am-elisengarten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2023\\\/01\\\/19\\\/galerie-am-elisengarten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/EIA_GaEg.jpg\",\"contentUrl\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/EIA_GaEg.jpg\",\"width\":530,\"height\":617,\"caption\":\"Galerie Am Elisengarten\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2023\\\/01\\\/19\\\/galerie-am-elisengarten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Galerie Am Elisengarten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/\",\"name\":\"Einkaufen in Aachen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/#\\\/schema\\\/person\\\/e7e4ecf5a1b2dcc107deec3ae378ee7e\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/author\\\/einkaufen-in-aachen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Galerie Am Elisengarten - Einkaufen in Aachen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aachen-shopping.de\/fr\/2023\/01\/19\/galerie-am-elisengarten\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aachen-shopping.de\/fr\/2023\/01\/19\/galerie-am-elisengarten\/#article","isPartOf":{"@id":"https:\/\/aachen-shopping.de\/fr\/2023\/01\/19\/galerie-am-elisengarten\/"},"author":{"name":"admin","@id":"https:\/\/aachen-shopping.de\/fr\/#\/schema\/person\/e7e4ecf5a1b2dcc107deec3ae378ee7e"},"headline":"Galerie Am Elisengarten","datePublished":"2023-01-19T10:08:32+00:00","mainEntityOfPage":{"@id":"https:\/\/aachen-shopping.de\/fr\/2023\/01\/19\/galerie-am-elisengarten\/"},"wordCount":536,"image":{"@id":"https:\/\/aachen-shopping.de\/fr\/2023\/01\/19\/galerie-am-elisengarten\/#primaryimage"},"thumbnailUrl":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2023\/01\/EIA_GaEg.jpg","articleSection":["SHOPPING-NEWS"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/aachen-shopping.de\/fr\/2023\/01\/19\/galerie-am-elisengarten\/","url":"https:\/\/aachen-shopping.de\/fr\/2023\/01\/19\/galerie-am-elisengarten\/","name":"Galerie Am Elisengarten - Einkaufen in Aachen","isPartOf":{"@id":"https:\/\/aachen-shopping.de\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aachen-shopping.de\/fr\/2023\/01\/19\/galerie-am-elisengarten\/#primaryimage"},"image":{"@id":"https:\/\/aachen-shopping.de\/fr\/2023\/01\/19\/galerie-am-elisengarten\/#primaryimage"},"thumbnailUrl":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2023\/01\/EIA_GaEg.jpg","datePublished":"2023-01-19T10:08:32+00:00","author":{"@id":"https:\/\/aachen-shopping.de\/fr\/#\/schema\/person\/e7e4ecf5a1b2dcc107deec3ae378ee7e"},"breadcrumb":{"@id":"https:\/\/aachen-shopping.de\/fr\/2023\/01\/19\/galerie-am-elisengarten\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aachen-shopping.de\/fr\/2023\/01\/19\/galerie-am-elisengarten\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aachen-shopping.de\/fr\/2023\/01\/19\/galerie-am-elisengarten\/#primaryimage","url":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2023\/01\/EIA_GaEg.jpg","contentUrl":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2023\/01\/EIA_GaEg.jpg","width":530,"height":617,"caption":"Galerie Am Elisengarten"},{"@type":"BreadcrumbList","@id":"https:\/\/aachen-shopping.de\/fr\/2023\/01\/19\/galerie-am-elisengarten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aachen-shopping.de\/fr\/"},{"@type":"ListItem","position":2,"name":"Galerie Am Elisengarten"}]},{"@type":"WebSite","@id":"https:\/\/aachen-shopping.de\/fr\/#website","url":"https:\/\/aachen-shopping.de\/fr\/","name":"Einkaufen in Aachen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aachen-shopping.de\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/aachen-shopping.de\/fr\/#\/schema\/person\/e7e4ecf5a1b2dcc107deec3ae378ee7e","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/aachen-shopping.de\/fr\/author\/einkaufen-in-aachen\/"}]}},"_links":{"self":[{"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/posts\/30158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/comments?post=30158"}],"version-history":[{"count":0,"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/posts\/30158\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/media\/30147"}],"wp:attachment":[{"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/media?parent=30158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/categories?post=30158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/tags?post=30158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}