{"id":32619,"date":"2024-03-19T08:54:08","date_gmt":"2024-03-19T07:54:08","guid":{"rendered":"https:\/\/aachen-shopping.de\/2024\/03\/19\/shokunin-kochmesser-und-werkzeuge-aus-der-ganze-welt-und-aus-aachen\/"},"modified":"2026-04-08T08:37:20","modified_gmt":"2026-04-08T06:37:20","slug":"shokunin-kochmesser-aus-der-ganzen-welt-und-aachen","status":"publish","type":"post","link":"https:\/\/aachen-shopping.de\/fr\/2024\/03\/19\/shokunin-kochmesser-aus-der-ganzen-welt-und-aachen\/","title":{"rendered":"Shokunin"},"content":{"rendered":"<h2>Shokunin \u2013 f\u00fcr Handwerker, Gartenfans und Messerliebhaber<\/h2>\n<p><strong>Kochmesser und Werkzeuge aus der ganzen Welt \u2013 und aus Aachen.<\/strong> Die Geschichte beginnt in einer Kneipe in K\u00f6ln: Der Vater von Markus Pr\u00f6mper trifft einen japanischen Handlungsreisenden. Sie kommen ins Gespr\u00e4ch, eine Freundschaft entsteht zwischen dem deutschen Schreinermeister und dem Japaner. Dieser kommt zuf\u00e4llig aus einem Ort in Japan, wo traditionelles Schreinerwerkzeug und japanische Messer gefertigt werden. Die Gesch\u00e4ftsidee ist geboren: Import von japanischem Schreinerwerkzeug. Und die Idee lebt noch immer\u2013 im wundervollen Laden SHOKUNIN (jap. f\u00fcr Handwerker) von Markus Pr\u00f6mper. N\u00e4chstes Jahr feiert Shokunin sein 30-j\u00e4hriges Jubil\u00e4um. \u2028Aus pers\u00f6nlichen Gr\u00fcnden hatte es Markus Pr\u00f6mper und seinen Laden 2006 von K\u00f6ln nach Aachen verschlagen \u2013 erst an den Pontdriesch, dann auf die Rennbahn, wo wir ihn besuchen.<\/p>\n<h4>Messer aus aller Herren L\u00e4nder<\/h4>\n<p>Unser erster Eindruck im SHOKUNIN: Kochmesser, soweit das Auge reicht. In erster Linie japanische Messer (jap. \u201eHocho\u201c) mit den klangvollen Namen Santoku, Nakiri, Gyoto, Usuba oder Sashimi. G\u00fcnstige \u201eEinsteigermesser\u201c, kunstvoll geschmiedete, wertvolle Damaszener-Messer mit mehr als 100-fach gefalteter Klinge \u2013 Messer f\u00fcr rohen Fisch, Gem\u00fcse, einseitig oder beidseitig geschliffene Messer \u2026\u2028Wir finden aber auch Messer anderer Nationen im Ladenlokal:<br \/>\nMesser aus Spanien der Marke Pallar\u00e8s Solsona \u2013 in Solsona hat die Messerindustrie eine Tradition, die bis ins sechzehnte Jahrhundert zur\u00fcckreicht. Messer aus Solingen, geschmiedet aus Carbonstahl mit Blattdekor und Griffen aus Kirsch- oder Olivenholz, kr\u00e4ftige Brotmesser, ein h\u00fcbsches Sortiment Opinel-Messer aus Frankreich.<br \/>\nMesser der Marke BLACK CHILI, einer Berliner Firma, die in Vietnam Messer aus alten LKW-Blattfedern herstellen l\u00e4sst \u2013 rustikal, recycled, ungew\u00f6hnlich. &#8220;Das finden insbesondere junge Menschen gut, die hohen Wert auf Nachhaltigkeit legen&#8221;, so der Inhaber.<br \/>\nUnd sogar Messer \u201eMade in Aachen\u201c finden wir: Produkte des jungen Aachener Messerschmieds Hristiyan Dakov \u2013 von Griff bis Klinge Handarbeit.<\/p>\n<h4>F\u00fcr Messer-Neulinge und alte Hasen<\/h4>\n<p>Sowohl \u201eMesser-Neulinge\u201c als auch \u201ealte Hasen\u201c, die sich ein besonderes Messer g\u00f6nnen m\u00f6chten, werden bei SHOKUNIN f\u00fcndig. Einsteigermesser gef\u00e4llig? Markus Pr\u00f6mper empfiehlt ein Santoku Hocho mit drei Lagen. Santoku hei\u00dft \u201edrei Tugenden\u201c \u2013 es ist das Allzweckmesser der japanischen K\u00fcche: passend f\u00fcr das Schneiden von Fleisch, Fisch und Gem\u00fcse. Und daf\u00fcr muss man kein Verm\u00f6gen ausgeben!<\/p>\n<p>Passend zu den zahlreichen Schleifsteinen gibt es im SHOKUNIN regelm\u00e4\u00dfig Kochmesser-Sch\u00e4rfkurse &#8211; an denen gerne M\u00e4nner und Frauen teilnehmen. \u00dcbrigens sind die Frauen hier oft die geschickteren Schleifer, da sie mehr Feingef\u00fchl und Geduld haben und weniger mit Kraft arbeiten.<\/p>\n<h4>Schreinerwerkzeuge mit Tradition<\/h4>\n<p>Den Wurzeln der Gesch\u00e4ftsidee folgend, sind auch die handgeschmiedeten Schreinerwerkzeuge Teil des Sortiments:<br \/>\nJapanische Stemmeisen (\u201eOire Nomi\u201c) \u2013 2-lagig geschmiedet, japanische H\u00e4mmer (jap. \u201eGenno\u201c) mit achteckigem Kopf in verschiedenen Gewichtsklassen, Hobel f\u00fcr viele Anwendungen, Schreiners\u00e4gen, die auf Zug arbeiten und damit viel pr\u00e4ziseres und einfacheres Arbeiten mit weniger Kraftaufwand m\u00f6glich machen. Sch\u00f6n, klassisch und leistungsstark vereinen sie \u00c4sthetik mit Alltagstauglichkeit.<\/p>\n<h4>Augenschmaus f\u00fcr Gartenliebhaber<\/h4>\n<p>Auch Gartenliebhaber werden f\u00fcndig, denn Markus Pr\u00f6mper ist auch Fachmann f\u00fcr Gartenwerkzeuge aus Japan: traditionelle Bonsai-Scheren, Pflanzhacken, Erntesicheln, robuste Pflanzmesser, die auf den Namen \u201eHori Hori\u201c (= \u201egraben graben\u201c) h\u00f6ren \u2013 abgerundete, stabile Stahlklinge mit gezackter Kante, eine scharfen Kante \u2013 zum Pflanzen, Verpflanzen, Graben, Schneiden oder Unkraut entfernen.<br \/>\nUnser Lieblingsprodukt: die japanische Baums\u00e4ge \u201eBigBoy\u201c, mit 36 cm S\u00e4geblatt \u2013 m\u00e4chtig, aber klappbar, f\u00fcr 75 Euro. Wer\u2019s kleiner mag: es gibt auch den \u201ePocketBoy\u201c mit 17 cm Schneide f\u00fcr Garten, Wandern oder Camping.<\/p>\n<p>Und wer ein kleines Geschenk sucht: Markus Pr\u00f6mer bietet auch Produkte rund um das Thema \u201eTischkultur\u201c an, z.B. Schneidebretter, Kochzangen, Untersetzer oder wiederbeschreibbare Serviettenringe der Marke \u201eside by side\u201c. Entw\u00fcrfe von Designern, produziert von Werkst\u00e4tten f\u00fcr Menschen mit Behinderung aus S\u00fcddeutschland.<\/p>\n<p>Und zum Abschluss noch eine gro\u00dfe Bitte des Messer-Profis: Bitte stellt eure Messer NIE in die Sp\u00fclmaschine &#8211; sie werden es mit Sch\u00e4rfe und gutem Aussehen danken ;o)!<\/p>\n<hr \/>\n<p><span style=\"font-size: 8pt;\">(Fotos: Marie-Luise Manthei)<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Markus Pr\u00f6mper bietet Klingen mit atemberaubender Sch\u00e4rfe aus der ganzen Welt \u2013 und aus Aachen!<\/p>\n","protected":false},"author":1,"featured_media":32604,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-32619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-shopping-news-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Shokunin - Einkaufen in Aachen<\/title>\n<meta name=\"description\" content=\"Shokunin \u2013 Kochmesser und Werkzeuge aus der ganze Welt und aus Aachen. Klingen mit atemberaubender Sch\u00e4rfe aus Japan, Thailand, Spanien \u2013 und aus Aachen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aachen-shopping.de\/fr\/2024\/03\/19\/shokunin-kochmesser-aus-der-ganzen-welt-und-aachen\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2024\\\/03\\\/19\\\/shokunin-kochmesser-aus-der-ganzen-welt-und-aachen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2024\\\/03\\\/19\\\/shokunin-kochmesser-aus-der-ganzen-welt-und-aachen\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/#\\\/schema\\\/person\\\/e7e4ecf5a1b2dcc107deec3ae378ee7e\"},\"headline\":\"Shokunin\",\"datePublished\":\"2024-03-19T07:54:08+00:00\",\"dateModified\":\"2026-04-08T06:37:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2024\\\/03\\\/19\\\/shokunin-kochmesser-aus-der-ganzen-welt-und-aachen\\\/\"},\"wordCount\":665,\"image\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2024\\\/03\\\/19\\\/shokunin-kochmesser-aus-der-ganzen-welt-und-aachen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/EIA_Shokunin.jpg\",\"articleSection\":[\"SHOPPING-NEWS\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2024\\\/03\\\/19\\\/shokunin-kochmesser-aus-der-ganzen-welt-und-aachen\\\/\",\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2024\\\/03\\\/19\\\/shokunin-kochmesser-aus-der-ganzen-welt-und-aachen\\\/\",\"name\":\"Shokunin - Einkaufen in Aachen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2024\\\/03\\\/19\\\/shokunin-kochmesser-aus-der-ganzen-welt-und-aachen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2024\\\/03\\\/19\\\/shokunin-kochmesser-aus-der-ganzen-welt-und-aachen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/EIA_Shokunin.jpg\",\"datePublished\":\"2024-03-19T07:54:08+00:00\",\"dateModified\":\"2026-04-08T06:37:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/#\\\/schema\\\/person\\\/e7e4ecf5a1b2dcc107deec3ae378ee7e\"},\"description\":\"Shokunin \u2013 Kochmesser und Werkzeuge aus der ganze Welt und aus Aachen. Klingen mit atemberaubender Sch\u00e4rfe aus Japan, Thailand, Spanien \u2013 und aus Aachen!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2024\\\/03\\\/19\\\/shokunin-kochmesser-aus-der-ganzen-welt-und-aachen\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2024\\\/03\\\/19\\\/shokunin-kochmesser-aus-der-ganzen-welt-und-aachen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2024\\\/03\\\/19\\\/shokunin-kochmesser-aus-der-ganzen-welt-und-aachen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/EIA_Shokunin.jpg\",\"contentUrl\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/EIA_Shokunin.jpg\",\"width\":530,\"height\":617,\"caption\":\"Shokunin Aachen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2024\\\/03\\\/19\\\/shokunin-kochmesser-aus-der-ganzen-welt-und-aachen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shokunin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/\",\"name\":\"Einkaufen in Aachen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/#\\\/schema\\\/person\\\/e7e4ecf5a1b2dcc107deec3ae378ee7e\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/author\\\/einkaufen-in-aachen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Shokunin - Einkaufen in Aachen","description":"Shokunin \u2013 Kochmesser und Werkzeuge aus der ganze Welt und aus Aachen. Klingen mit atemberaubender Sch\u00e4rfe aus Japan, Thailand, Spanien \u2013 und aus Aachen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aachen-shopping.de\/fr\/2024\/03\/19\/shokunin-kochmesser-aus-der-ganzen-welt-und-aachen\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aachen-shopping.de\/fr\/2024\/03\/19\/shokunin-kochmesser-aus-der-ganzen-welt-und-aachen\/#article","isPartOf":{"@id":"https:\/\/aachen-shopping.de\/fr\/2024\/03\/19\/shokunin-kochmesser-aus-der-ganzen-welt-und-aachen\/"},"author":{"name":"admin","@id":"https:\/\/aachen-shopping.de\/fr\/#\/schema\/person\/e7e4ecf5a1b2dcc107deec3ae378ee7e"},"headline":"Shokunin","datePublished":"2024-03-19T07:54:08+00:00","dateModified":"2026-04-08T06:37:20+00:00","mainEntityOfPage":{"@id":"https:\/\/aachen-shopping.de\/fr\/2024\/03\/19\/shokunin-kochmesser-aus-der-ganzen-welt-und-aachen\/"},"wordCount":665,"image":{"@id":"https:\/\/aachen-shopping.de\/fr\/2024\/03\/19\/shokunin-kochmesser-aus-der-ganzen-welt-und-aachen\/#primaryimage"},"thumbnailUrl":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2024\/03\/EIA_Shokunin.jpg","articleSection":["SHOPPING-NEWS"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/aachen-shopping.de\/fr\/2024\/03\/19\/shokunin-kochmesser-aus-der-ganzen-welt-und-aachen\/","url":"https:\/\/aachen-shopping.de\/fr\/2024\/03\/19\/shokunin-kochmesser-aus-der-ganzen-welt-und-aachen\/","name":"Shokunin - Einkaufen in Aachen","isPartOf":{"@id":"https:\/\/aachen-shopping.de\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aachen-shopping.de\/fr\/2024\/03\/19\/shokunin-kochmesser-aus-der-ganzen-welt-und-aachen\/#primaryimage"},"image":{"@id":"https:\/\/aachen-shopping.de\/fr\/2024\/03\/19\/shokunin-kochmesser-aus-der-ganzen-welt-und-aachen\/#primaryimage"},"thumbnailUrl":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2024\/03\/EIA_Shokunin.jpg","datePublished":"2024-03-19T07:54:08+00:00","dateModified":"2026-04-08T06:37:20+00:00","author":{"@id":"https:\/\/aachen-shopping.de\/fr\/#\/schema\/person\/e7e4ecf5a1b2dcc107deec3ae378ee7e"},"description":"Shokunin \u2013 Kochmesser und Werkzeuge aus der ganze Welt und aus Aachen. Klingen mit atemberaubender Sch\u00e4rfe aus Japan, Thailand, Spanien \u2013 und aus Aachen!","breadcrumb":{"@id":"https:\/\/aachen-shopping.de\/fr\/2024\/03\/19\/shokunin-kochmesser-aus-der-ganzen-welt-und-aachen\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aachen-shopping.de\/fr\/2024\/03\/19\/shokunin-kochmesser-aus-der-ganzen-welt-und-aachen\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aachen-shopping.de\/fr\/2024\/03\/19\/shokunin-kochmesser-aus-der-ganzen-welt-und-aachen\/#primaryimage","url":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2024\/03\/EIA_Shokunin.jpg","contentUrl":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2024\/03\/EIA_Shokunin.jpg","width":530,"height":617,"caption":"Shokunin Aachen"},{"@type":"BreadcrumbList","@id":"https:\/\/aachen-shopping.de\/fr\/2024\/03\/19\/shokunin-kochmesser-aus-der-ganzen-welt-und-aachen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aachen-shopping.de\/fr\/"},{"@type":"ListItem","position":2,"name":"Shokunin"}]},{"@type":"WebSite","@id":"https:\/\/aachen-shopping.de\/fr\/#website","url":"https:\/\/aachen-shopping.de\/fr\/","name":"Einkaufen in Aachen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aachen-shopping.de\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/aachen-shopping.de\/fr\/#\/schema\/person\/e7e4ecf5a1b2dcc107deec3ae378ee7e","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/aachen-shopping.de\/fr\/author\/einkaufen-in-aachen\/"}]}},"_links":{"self":[{"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/posts\/32619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/comments?post=32619"}],"version-history":[{"count":4,"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/posts\/32619\/revisions"}],"predecessor-version":[{"id":35610,"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/posts\/32619\/revisions\/35610"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/media\/32604"}],"wp:attachment":[{"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/media?parent=32619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/categories?post=32619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/tags?post=32619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}