{"id":6383,"date":"2016-04-28T08:27:13","date_gmt":"2016-04-28T06:27:13","guid":{"rendered":"http:\/\/aachen-shopping.de\/fr\/2016\/04\/28\/schenken-durch-shoppen\/"},"modified":"2016-04-28T08:27:13","modified_gmt":"2016-04-28T06:27:13","slug":"schenken-durch-shoppen","status":"publish","type":"post","link":"https:\/\/aachen-shopping.de\/fr\/2016\/04\/28\/schenken-durch-shoppen\/","title":{"rendered":"Schenken durch Shoppen"},"content":{"rendered":"<hr \/>\n<p><strong>So sch\u00f6n war helfen noch nie: Wer bei Oxfam shoppt, tut sich und anderen etwas Gutes.\u00a0 <\/strong><\/p>\n<hr \/>\n<p>\u201eF\u00fcr eine gerechte Welt. Ohne Armut\u201c \u2013 so lautet der Slogan der globalen Nothilfe- und Entwicklungsorganisation Oxfam Deutschland. Der neue Oxfam Shop am Theaterplatz sorgt daf\u00fcr, dass sich die Aachener mit einem Einkauf im Store f\u00fcr Klimaschutz, gerechte Arbeitsbedingungen und Frauenrechte in Entwicklungsl\u00e4ndern, einsetzten k\u00f6nnen.<\/p>\n<p><strong>Das bewegt Oxfam<br \/>\n<\/strong>Die Organisation hilft Menschen in Not, unterst\u00fctzt bei Krisen und Katastrophen. Auch arbeitet sie in \u00fcber 90 L\u00e4ndern daran, die Verf\u00fcgbarkeit von Land und Wasser zu sichern und hilft bei Bildung und Gesundheitsversorgung.<\/p>\n<p><strong>Unterst\u00fctzung<\/strong><br \/>\nSeit Anfang des Monats werden gespendete Kleidung, Haushaltsgegenst\u00e4nde, B\u00fccher und Medien im Oxfam Shop am Theaterplatz 15 weiterverkauft. Das eingenommene Geld kommt der Nothilfe, den Entwicklungsprojekten sowie der Kampagnenarbeit von Oxfam Deutschland e.V. zugute.<\/p>\n<p>Wer sich dar\u00fcber hinaus engagieren m\u00f6chte, kann auch ehrenamtlich mitarbeiten. Ob Kunde oder Ehrenamtler \u2013 bei Oxfam kann jeder dazu beitragen, die Welt ein bisschen besser zu machen.<\/p>\n<hr \/>\n<p>Hier geht es zur Internetseite von Oxfam:<a href=\"https:\/\/www.oxfam.de\/\" target=\"_blank\"> www.oxfam.de<\/a><\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>So sch\u00f6n war helfen noch nie: Wer bei Oxfam shoppt, tut sich und anderen etwas Gutes.  <\/p>\n","protected":false},"author":1,"featured_media":6272,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-6383","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-shopping-news-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Schenken durch Shoppen - Einkaufen in Aachen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aachen-shopping.de\/fr\/2016\/04\/28\/schenken-durch-shoppen\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2016\\\/04\\\/28\\\/schenken-durch-shoppen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2016\\\/04\\\/28\\\/schenken-durch-shoppen\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/#\\\/schema\\\/person\\\/e7e4ecf5a1b2dcc107deec3ae378ee7e\"},\"headline\":\"Schenken durch Shoppen\",\"datePublished\":\"2016-04-28T06:27:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2016\\\/04\\\/28\\\/schenken-durch-shoppen\\\/\"},\"wordCount\":185,\"image\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2016\\\/04\\\/28\\\/schenken-durch-shoppen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/EIA_Oxfam-1.jpg\",\"articleSection\":[\"SHOPPING-NEWS\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2016\\\/04\\\/28\\\/schenken-durch-shoppen\\\/\",\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2016\\\/04\\\/28\\\/schenken-durch-shoppen\\\/\",\"name\":\"Schenken durch Shoppen - Einkaufen in Aachen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2016\\\/04\\\/28\\\/schenken-durch-shoppen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2016\\\/04\\\/28\\\/schenken-durch-shoppen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/EIA_Oxfam-1.jpg\",\"datePublished\":\"2016-04-28T06:27:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/#\\\/schema\\\/person\\\/e7e4ecf5a1b2dcc107deec3ae378ee7e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2016\\\/04\\\/28\\\/schenken-durch-shoppen\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2016\\\/04\\\/28\\\/schenken-durch-shoppen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2016\\\/04\\\/28\\\/schenken-durch-shoppen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/EIA_Oxfam-1.jpg\",\"contentUrl\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/EIA_Oxfam-1.jpg\",\"width\":447,\"height\":312},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/2016\\\/04\\\/28\\\/schenken-durch-shoppen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schenken durch Shoppen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/\",\"name\":\"Einkaufen in Aachen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/#\\\/schema\\\/person\\\/e7e4ecf5a1b2dcc107deec3ae378ee7e\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/fr\\\/author\\\/einkaufen-in-aachen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schenken durch Shoppen - Einkaufen in Aachen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aachen-shopping.de\/fr\/2016\/04\/28\/schenken-durch-shoppen\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aachen-shopping.de\/fr\/2016\/04\/28\/schenken-durch-shoppen\/#article","isPartOf":{"@id":"https:\/\/aachen-shopping.de\/fr\/2016\/04\/28\/schenken-durch-shoppen\/"},"author":{"name":"admin","@id":"https:\/\/aachen-shopping.de\/fr\/#\/schema\/person\/e7e4ecf5a1b2dcc107deec3ae378ee7e"},"headline":"Schenken durch Shoppen","datePublished":"2016-04-28T06:27:13+00:00","mainEntityOfPage":{"@id":"https:\/\/aachen-shopping.de\/fr\/2016\/04\/28\/schenken-durch-shoppen\/"},"wordCount":185,"image":{"@id":"https:\/\/aachen-shopping.de\/fr\/2016\/04\/28\/schenken-durch-shoppen\/#primaryimage"},"thumbnailUrl":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2016\/04\/EIA_Oxfam-1.jpg","articleSection":["SHOPPING-NEWS"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/aachen-shopping.de\/fr\/2016\/04\/28\/schenken-durch-shoppen\/","url":"https:\/\/aachen-shopping.de\/fr\/2016\/04\/28\/schenken-durch-shoppen\/","name":"Schenken durch Shoppen - Einkaufen in Aachen","isPartOf":{"@id":"https:\/\/aachen-shopping.de\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aachen-shopping.de\/fr\/2016\/04\/28\/schenken-durch-shoppen\/#primaryimage"},"image":{"@id":"https:\/\/aachen-shopping.de\/fr\/2016\/04\/28\/schenken-durch-shoppen\/#primaryimage"},"thumbnailUrl":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2016\/04\/EIA_Oxfam-1.jpg","datePublished":"2016-04-28T06:27:13+00:00","author":{"@id":"https:\/\/aachen-shopping.de\/fr\/#\/schema\/person\/e7e4ecf5a1b2dcc107deec3ae378ee7e"},"breadcrumb":{"@id":"https:\/\/aachen-shopping.de\/fr\/2016\/04\/28\/schenken-durch-shoppen\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aachen-shopping.de\/fr\/2016\/04\/28\/schenken-durch-shoppen\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aachen-shopping.de\/fr\/2016\/04\/28\/schenken-durch-shoppen\/#primaryimage","url":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2016\/04\/EIA_Oxfam-1.jpg","contentUrl":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2016\/04\/EIA_Oxfam-1.jpg","width":447,"height":312},{"@type":"BreadcrumbList","@id":"https:\/\/aachen-shopping.de\/fr\/2016\/04\/28\/schenken-durch-shoppen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aachen-shopping.de\/fr\/"},{"@type":"ListItem","position":2,"name":"Schenken durch Shoppen"}]},{"@type":"WebSite","@id":"https:\/\/aachen-shopping.de\/fr\/#website","url":"https:\/\/aachen-shopping.de\/fr\/","name":"Einkaufen in Aachen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aachen-shopping.de\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/aachen-shopping.de\/fr\/#\/schema\/person\/e7e4ecf5a1b2dcc107deec3ae378ee7e","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/aachen-shopping.de\/fr\/author\/einkaufen-in-aachen\/"}]}},"_links":{"self":[{"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/posts\/6383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/comments?post=6383"}],"version-history":[{"count":0,"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/posts\/6383\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/media\/6272"}],"wp:attachment":[{"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/media?parent=6383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/categories?post=6383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aachen-shopping.de\/fr\/wp-json\/wp\/v2\/tags?post=6383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}