{"id":23726,"date":"2020-09-23T08:36:36","date_gmt":"2020-09-23T06:36:36","guid":{"rendered":"https:\/\/aachen-shopping.de\/2020\/09\/23\/clou-papeterie-geschenke\/"},"modified":"2020-11-06T08:49:23","modified_gmt":"2020-11-06T07:49:23","slug":"clou-papeterie-geschenke","status":"publish","type":"post","link":"https:\/\/aachen-shopping.de\/nl\/2020\/09\/23\/clou-papeterie-geschenke\/","title":{"rendered":"Clou \u2013 Papeterie &#038; Geschenke"},"content":{"rendered":"<p><em><br \/>\u201eGeh doch mal zu Clou, da findet man immer was.\u201c Den Tipp haben bestimmt viele Aachener schon bekommen, denn in dem bunten Laden unweit des Doms wird wirklich jeder f\u00fcndig, der sich selbst oder jemand anders beschenken m\u00f6chte.<\/em><\/p>\r\n<p>&nbsp;<\/p>\r\n<p>Wer es an den Kartenst\u00e4ndern mit den zahllosen originellen Postkarten vorbei bis in den Laden mit den gro\u00dfen Schaufenstern geschafft hat, wird geradezu \u00fcberw\u00e4ltigt von der riesigen Auswahl an ausgefallenen, witzigen und praktischen \u201eGebrauchswaren in unerwartetem Design.\u201c So dr\u00fcckt es Karl-Martin Ockewitz aus, der das Gesch\u00e4ft am Klosterplatz 1994 er\u00f6ffnete. Eigentlich wollte er Lehrer f\u00fcr Sport und Deutsch werden, \u201eaber dann bin ich \u00fcber einen Freund ans Handeln gekommen.\u201c Nach seinem Referendariat half er beim \u201ePurzelbaum\u201c aus, einem Spielwarengesch\u00e4ft. Er fand Gefallen an der Arbeit und lernte auch gleich die ersten Firmen kennen. Als dann das Ladenlokal in direkter N\u00e4he zu Dom und Markt frei wurde, griff er kurzentschlossen zu und er\u00f6ffnete den \u201eClou\u201c. Eine Schatzkammer f\u00fcr Geschenke gegen\u00fcber der Domschatzkammer sozusagen. \u00a0<\/p>\r\n<p>&nbsp;<\/p>\r\n<h3>Bunt, verspielt, ausgefallen, ungew\u00f6hnlich<\/h3>\r\n<p>Auf rund 90 Quadratmetern findet man hier hochwertige Papierwaren und Pr\u00e4sente von Remember, Artebene, R\u00e4der und anderen Firmen, modische Accessoires, handgemachte Lampenschirme einer griechischen K\u00fcnstlerin, Stifte, Spardosen, Taschen, B\u00fcroartikel, Schmuck, ungleiche Sockenpaare, Haushaltshelfer und vieles, vieles mehr. Bunt, verspielt, ausgefallen, ungew\u00f6hnlich \u2013 das sind die Kriterien nach denen Karl-Martin Ockewitz entscheidet, was den Weg in seine Regale findet. Er sucht auf Messen und bei einzelnen Firmen alles selbst aus, gerade bei Postkarten sind es oft nur einzelne Motive oder Serien, die er ausw\u00e4hlt. Nicht umsonst ist \u201eClou\u201c ber\u00fchmt f\u00fcr seine originellen Karten, manche davon von einem Aachener Fotografen. Hier gibt es zu jedem Anlass und zu jeder Gelegenheit die passende Karte. \u00a0<\/p>\r\n<p>&nbsp;<\/p>\r\n<h3>Umweltschonende Produkte aus neuen Materialien<\/h3>\r\n<p>Karl-Martin Ockewitz hat inzwischen einen Riecher daf\u00fcr, was gut ankommt, richtet sich aber vorwiegend nach seinem eigenen Geschmack. Manche Sachen will er nicht im Gesch\u00e4ft haben \u2013 egal, ob sie gerade im Trend sind \u2013 wenn sie nicht in das Konzept des Ladens passen. \u201eWichtig ist, dass es immer neue Ideen, \u00fcberraschende Designs gibt, dass man schnell ist, von Trends aber auch fr\u00fch genug wieder abspringt,\u201c erkl\u00e4rt er. Ein Renner waren die kurzen bunten Wickelr\u00f6cke, sogenannte Cacheurs, Fotoalben hingegen werden kaum noch verkauft. Auch auf die Nachfrage nach umweltschonenden Produkten stellt er sich ein, so gibt es bei Clou nun eine umweltbewusste Produktlinie, etwa To-go-Becher, Thermobecher, und Beh\u00e4ltnisse aus einem neuen Material auf Basis von Pflanzenzucker. Nat\u00fcrlich ist das Internet eine gro\u00dfe Konkurrenz, aber Karl-Martin Ockewitz versucht, durch eine gute Beratung und eine moderate Preisgestaltung zu bestehen. Zudem lebt sein Gesch\u00e4ft besonders von spontanen Kaufentscheidungen und davon, dass die Kunden die Artikel anfassen und manchmal auch ausprobieren k\u00f6nnen. Der \u201eClou\u201c zieht besonders Frauen an, best\u00e4tigt Karl-Martin Ockewitz. In der Weihnachtszeit brummt der Laden besonders. \u201eDann hab ich allerdings vor allem M\u00e4nner im Laden, die schnell noch Geschenke besorgen m\u00fcssen,\u201c lacht er, \u201eund die Sachen werden hier nat\u00fcrlich auch direkt liebevoll verpackt.\u201c \u00a0<\/p>\r\n<hr class=\"wp-block-separator\" \/><!-- \/wp:post-content -->\r\n\r\n<!-- wp:paragraph {\"fontSize\":\"small\"} -->\r\n<p class=\"has-small-font-size\"><span style=\"font-size: 8pt;\">Fotos: Einkaufen in Aachen\/Marie-Luise Manthei<\/span><\/p>\r\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>\u201eGeh doch mal zu Clou, da findet man immer was.\u201c Den Tipp haben bestimmt schon viele Aachener bekommen Wir haben&#8217;s getan.<\/p>\n","protected":false},"author":1,"featured_media":23992,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8],"tags":[39,426,427,428],"class_list":["post-23726","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-shopping-news-nl","tag-aachen-nl","tag-clou-nl","tag-geschenke-nl","tag-papeterie-nl"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Clou \u2013 Papeterie &amp; Geschenke - Einkaufen in Aachen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aachen-shopping.de\/nl\/2020\/09\/23\/clou-papeterie-geschenke\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/2020\\\/09\\\/23\\\/clou-papeterie-geschenke\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/2020\\\/09\\\/23\\\/clou-papeterie-geschenke\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/#\\\/schema\\\/person\\\/e7e4ecf5a1b2dcc107deec3ae378ee7e\"},\"headline\":\"Clou \u2013 Papeterie &#038; Geschenke\",\"datePublished\":\"2020-09-23T06:36:36+00:00\",\"dateModified\":\"2020-11-06T07:49:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/2020\\\/09\\\/23\\\/clou-papeterie-geschenke\\\/\"},\"wordCount\":526,\"image\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/2020\\\/09\\\/23\\\/clou-papeterie-geschenke\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/EIA_Cl-1.jpg\",\"keywords\":[\"Aachen\",\"Clou\",\"Geschenke\",\"Papeterie\"],\"articleSection\":[\"SHOPPEN-NIEUWS\"],\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/2020\\\/09\\\/23\\\/clou-papeterie-geschenke\\\/\",\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/2020\\\/09\\\/23\\\/clou-papeterie-geschenke\\\/\",\"name\":\"Clou \u2013 Papeterie & Geschenke - Einkaufen in Aachen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/2020\\\/09\\\/23\\\/clou-papeterie-geschenke\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/2020\\\/09\\\/23\\\/clou-papeterie-geschenke\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/EIA_Cl-1.jpg\",\"datePublished\":\"2020-09-23T06:36:36+00:00\",\"dateModified\":\"2020-11-06T07:49:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/#\\\/schema\\\/person\\\/e7e4ecf5a1b2dcc107deec3ae378ee7e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/2020\\\/09\\\/23\\\/clou-papeterie-geschenke\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/2020\\\/09\\\/23\\\/clou-papeterie-geschenke\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/2020\\\/09\\\/23\\\/clou-papeterie-geschenke\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/EIA_Cl-1.jpg\",\"contentUrl\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/EIA_Cl-1.jpg\",\"width\":530,\"height\":617},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/2020\\\/09\\\/23\\\/clou-papeterie-geschenke\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Clou \u2013 Papeterie &#038; Geschenke\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/\",\"name\":\"Einkaufen in Aachen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/#\\\/schema\\\/person\\\/e7e4ecf5a1b2dcc107deec3ae378ee7e\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/author\\\/einkaufen-in-aachen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Clou \u2013 Papeterie & Geschenke - Einkaufen in Aachen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aachen-shopping.de\/nl\/2020\/09\/23\/clou-papeterie-geschenke\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aachen-shopping.de\/nl\/2020\/09\/23\/clou-papeterie-geschenke\/#article","isPartOf":{"@id":"https:\/\/aachen-shopping.de\/nl\/2020\/09\/23\/clou-papeterie-geschenke\/"},"author":{"name":"admin","@id":"https:\/\/aachen-shopping.de\/nl\/#\/schema\/person\/e7e4ecf5a1b2dcc107deec3ae378ee7e"},"headline":"Clou \u2013 Papeterie &#038; Geschenke","datePublished":"2020-09-23T06:36:36+00:00","dateModified":"2020-11-06T07:49:23+00:00","mainEntityOfPage":{"@id":"https:\/\/aachen-shopping.de\/nl\/2020\/09\/23\/clou-papeterie-geschenke\/"},"wordCount":526,"image":{"@id":"https:\/\/aachen-shopping.de\/nl\/2020\/09\/23\/clou-papeterie-geschenke\/#primaryimage"},"thumbnailUrl":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2020\/09\/EIA_Cl-1.jpg","keywords":["Aachen","Clou","Geschenke","Papeterie"],"articleSection":["SHOPPEN-NIEUWS"],"inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/aachen-shopping.de\/nl\/2020\/09\/23\/clou-papeterie-geschenke\/","url":"https:\/\/aachen-shopping.de\/nl\/2020\/09\/23\/clou-papeterie-geschenke\/","name":"Clou \u2013 Papeterie & Geschenke - Einkaufen in Aachen","isPartOf":{"@id":"https:\/\/aachen-shopping.de\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aachen-shopping.de\/nl\/2020\/09\/23\/clou-papeterie-geschenke\/#primaryimage"},"image":{"@id":"https:\/\/aachen-shopping.de\/nl\/2020\/09\/23\/clou-papeterie-geschenke\/#primaryimage"},"thumbnailUrl":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2020\/09\/EIA_Cl-1.jpg","datePublished":"2020-09-23T06:36:36+00:00","dateModified":"2020-11-06T07:49:23+00:00","author":{"@id":"https:\/\/aachen-shopping.de\/nl\/#\/schema\/person\/e7e4ecf5a1b2dcc107deec3ae378ee7e"},"breadcrumb":{"@id":"https:\/\/aachen-shopping.de\/nl\/2020\/09\/23\/clou-papeterie-geschenke\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aachen-shopping.de\/nl\/2020\/09\/23\/clou-papeterie-geschenke\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/aachen-shopping.de\/nl\/2020\/09\/23\/clou-papeterie-geschenke\/#primaryimage","url":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2020\/09\/EIA_Cl-1.jpg","contentUrl":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2020\/09\/EIA_Cl-1.jpg","width":530,"height":617},{"@type":"BreadcrumbList","@id":"https:\/\/aachen-shopping.de\/nl\/2020\/09\/23\/clou-papeterie-geschenke\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aachen-shopping.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Clou \u2013 Papeterie &#038; Geschenke"}]},{"@type":"WebSite","@id":"https:\/\/aachen-shopping.de\/nl\/#website","url":"https:\/\/aachen-shopping.de\/nl\/","name":"Einkaufen in Aachen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aachen-shopping.de\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"https:\/\/aachen-shopping.de\/nl\/#\/schema\/person\/e7e4ecf5a1b2dcc107deec3ae378ee7e","name":"admin","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/aachen-shopping.de\/nl\/author\/einkaufen-in-aachen\/"}]}},"_links":{"self":[{"href":"https:\/\/aachen-shopping.de\/nl\/wp-json\/wp\/v2\/posts\/23726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aachen-shopping.de\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aachen-shopping.de\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aachen-shopping.de\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aachen-shopping.de\/nl\/wp-json\/wp\/v2\/comments?post=23726"}],"version-history":[{"count":0,"href":"https:\/\/aachen-shopping.de\/nl\/wp-json\/wp\/v2\/posts\/23726\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aachen-shopping.de\/nl\/wp-json\/wp\/v2\/media\/23992"}],"wp:attachment":[{"href":"https:\/\/aachen-shopping.de\/nl\/wp-json\/wp\/v2\/media?parent=23726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aachen-shopping.de\/nl\/wp-json\/wp\/v2\/categories?post=23726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aachen-shopping.de\/nl\/wp-json\/wp\/v2\/tags?post=23726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}