{"id":33024,"date":"2024-06-04T14:58:05","date_gmt":"2024-06-04T12:58:05","guid":{"rendered":"https:\/\/aachen-shopping.de\/2024\/06\/04\/volker-lang-accessoires\/"},"modified":"2024-06-13T13:46:51","modified_gmt":"2024-06-13T11:46:51","slug":"volker-lang-accessoires","status":"publish","type":"post","link":"https:\/\/aachen-shopping.de\/nl\/2024\/06\/04\/volker-lang-accessoires\/","title":{"rendered":"Volker Lang Accessoires"},"content":{"rendered":"<h2><strong>Taschen und Accessoires aus Leder<\/strong><\/h2>\n<p>\u201eIch wollte schon immer Farben machen, dann fing ich an in Orange, Gelb, Rot.\u201c, so Volker Lang, Mode-Designer, Gr\u00fcnder und Eigent\u00fcmer von Volker Lang Accessoires. Der geb\u00fcrtige Saarbr\u00fccker studierte in Hamburg Mode-Design und er\u00f6ffnete dort 1983 das \u201eKaufrausch\u201c, seines Wissens nach der erste Concept-Store in Deutschland. Er startete mit ma\u00dfgeschneiderter Lederbekleidung. Aus Lederresten n\u00e4hte er Taschen und Beutel, ver\u00e4nderte dann seine Entw\u00fcrfe in Richtung Portemonnaies. Er wollte leuchtende Farben \u2013 daraus entstand sein Markenzeichen: das farbige Leder.<br \/>\n\u201eCharlotte\u201c, so der Name seiner ersten Tasche, ist handlich, au\u00dfergew\u00f6hnlich, schlicht und ist nach wie vor Part der Kollektionen. Volker Langs Design ist \u2013 so sinniert er \u2013 \u00a0geradlinig, klar, deutsch.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Aachen \u2013 das Herz des Labels<br \/>\n<\/strong><\/h3>\n<p>Das Haupthaus in Aachen ist der Dreh- und Angelpunkt des Unternehmens. Design, Produktionssteuerung, Warenendkontrolle, Lager, Vertrieb und Marketing sind hier vereint. Inmitten des Unternehmensgeschehens ist St\u00f6bern und Shoppen der gesamten Kollektionen m\u00f6glich \u2013 zus\u00e4tzlich gibt es Sale-Schn\u00e4ppchen und auch Schals, H\u00fcte und Sonnenbrillen anderer Labels. Aber der Kern des Lang-Sortiments sind Handtaschen, Ledermappen, Kulturtaschen, Schl\u00fcsselanh\u00e4nger, Necessaires, G\u00fcrtel, Fotom\u00e4ppchen in vielen Farben und Formen. Sie werden nicht nur in Aachen, sondern auch in Bremen und Hamburg (Kaufrausch), im europ\u00e4ischen Ausland, sogar in Seoul und \u00fcber den Onlineshop in die ganze Welt verkauft.<\/p>\n<h3><\/h3>\n<h3><strong>\u201eNachhaltigkeit dr\u00fcckt sich auch in Haltbarkeit aus\u201c<\/strong><\/h3>\n<p>Volker Lang arbeitet mit Lederh\u00e4ndlern in Italien zusammen, sucht die Leder pers\u00f6nlich aus. Rind, Kalb, Ziege, Schaaf werden verarbeitet \u2013 keine Exoten. Die Vision des Unternehmens: Langlebige Objekte schaffen, gegen den schnellen Modestrom, gegen Massenproduktion. Dabei spielt auch der eigene Reparaturservice eine gro\u00dfe Rolle. \u201eNachhaltigkeit dr\u00fcckt sich auch in Haltbarkeit aus\u201c. In der kleinen Werkstatt an der Heinrichsallee werden kleine Reparaturen und Arbeiten \u2013 wie die Herstellung der bekannten Seepferdchen-Schl\u00fcsselanh\u00e4nger \u2013 umgesetzt.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>\u201eDas Wiederkehrende ist nicht dasselbe, es ist immer etwas Anderes.\u201c<\/strong><\/h3>\n<p>Der Designer hat bereits viele Str\u00f6me erlebt, mit geformt. So mit der legend\u00e4ren B\u00fcgeltasche, die sich durch zwei Metallkugeln am Verschluss von anderen Taschen absetzt. Als Volker Lang vor ungef\u00e4hr 15 Jahren damit die Welt der Taschen bereicherte, war dieses Design komplettes Neuland. Mittlerweile gibt es bei ihm den B\u00fcgelverschluss f\u00fcr verschiedene Taschenformen und auch Portemonnaies.<br \/>\nDer kreative Kopf, der bis heute auch selbst handwerklich t\u00e4tig ist, liebt die Zusammenarbeit mit seinem Team. Er holt Inspirationen aus vielen Quellen, probiert Entw\u00fcrfe aus, stellt diese seinen Mitarbeitenden vor, jede\/r betrachtet diese, gibt Input.<strong><br \/>\n<\/strong><\/p>\n<h3><\/h3>\n<h3><strong>\u201eMir ist ein Entwurf am liebsten, der aussieht wie ein alter Bekannter\u201c<\/strong><\/h3>\n<p>Eine Kombination aus Neuem und Bekanntem ist f\u00fcr Volker Lang perfekt. Mit der neuen Linie \u201eCube\u201c wagt er jedoch nun eine neue Ausrichtung: Kantig, eckig, kubisch.<\/p>\n<p>Das Sortiment ist mittlerweile so facettenreich und bunt wie ein botanischer Garten oder ein Paradiesvogel. Das Paradies-Thema finden wir auch immer wieder in der wundersch\u00f6nen Bemalung der gro\u00dfen Schaufenster an der Heinrichsallee \u2013 exklusiv gestaltet von Volker\u2019s Frau, Heidi Theissen-Lang.<\/p>\n<p>Ein paradiesisches Label f\u00fcr Taschen und Accessoires aus Leder!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Volker Langs Design ist geradlinig, klar, deutsch und kommt aus Aachen \u2026<\/p>\n","protected":false},"author":1,"featured_media":32978,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-33024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-shopping-news-nl"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Volker Lang Accessoires - Einkaufen in Aachen<\/title>\n<meta name=\"description\" content=\"Volker Lang Aachen, Handtaschen, Ledermappen, Kulturtaschen, Schl\u00fcsselanh\u00e4nger, Necessaires, G\u00fcrtel, Fotom\u00e4ppchen in vielen Farben und Formen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aachen-shopping.de\/nl\/2024\/06\/04\/volker-lang-accessoires\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/2024\\\/06\\\/04\\\/volker-lang-accessoires\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/2024\\\/06\\\/04\\\/volker-lang-accessoires\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/#\\\/schema\\\/person\\\/e7e4ecf5a1b2dcc107deec3ae378ee7e\"},\"headline\":\"Volker Lang Accessoires\",\"datePublished\":\"2024-06-04T12:58:05+00:00\",\"dateModified\":\"2024-06-13T11:46:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/2024\\\/06\\\/04\\\/volker-lang-accessoires\\\/\"},\"wordCount\":514,\"image\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/2024\\\/06\\\/04\\\/volker-lang-accessoires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/EIA_VL.jpg\",\"articleSection\":[\"SHOPPEN-NIEUWS\"],\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/2024\\\/06\\\/04\\\/volker-lang-accessoires\\\/\",\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/2024\\\/06\\\/04\\\/volker-lang-accessoires\\\/\",\"name\":\"Volker Lang Accessoires - Einkaufen in Aachen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/2024\\\/06\\\/04\\\/volker-lang-accessoires\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/2024\\\/06\\\/04\\\/volker-lang-accessoires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/EIA_VL.jpg\",\"datePublished\":\"2024-06-04T12:58:05+00:00\",\"dateModified\":\"2024-06-13T11:46:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/#\\\/schema\\\/person\\\/e7e4ecf5a1b2dcc107deec3ae378ee7e\"},\"description\":\"Volker Lang Aachen, Handtaschen, Ledermappen, Kulturtaschen, Schl\u00fcsselanh\u00e4nger, Necessaires, G\u00fcrtel, Fotom\u00e4ppchen in vielen Farben und Formen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/2024\\\/06\\\/04\\\/volker-lang-accessoires\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/2024\\\/06\\\/04\\\/volker-lang-accessoires\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/2024\\\/06\\\/04\\\/volker-lang-accessoires\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/EIA_VL.jpg\",\"contentUrl\":\"https:\\\/\\\/aachen-shopping.de\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/EIA_VL.jpg\",\"width\":530,\"height\":617,\"caption\":\"Volker Lang Einkaufen in Aachen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/2024\\\/06\\\/04\\\/volker-lang-accessoires\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Volker Lang Accessoires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/\",\"name\":\"Einkaufen in Aachen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/#\\\/schema\\\/person\\\/e7e4ecf5a1b2dcc107deec3ae378ee7e\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/aachen-shopping.de\\\/nl\\\/author\\\/einkaufen-in-aachen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Volker Lang Accessoires - Einkaufen in Aachen","description":"Volker Lang Aachen, Handtaschen, Ledermappen, Kulturtaschen, Schl\u00fcsselanh\u00e4nger, Necessaires, G\u00fcrtel, Fotom\u00e4ppchen in vielen Farben und Formen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aachen-shopping.de\/nl\/2024\/06\/04\/volker-lang-accessoires\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aachen-shopping.de\/nl\/2024\/06\/04\/volker-lang-accessoires\/#article","isPartOf":{"@id":"https:\/\/aachen-shopping.de\/nl\/2024\/06\/04\/volker-lang-accessoires\/"},"author":{"name":"admin","@id":"https:\/\/aachen-shopping.de\/nl\/#\/schema\/person\/e7e4ecf5a1b2dcc107deec3ae378ee7e"},"headline":"Volker Lang Accessoires","datePublished":"2024-06-04T12:58:05+00:00","dateModified":"2024-06-13T11:46:51+00:00","mainEntityOfPage":{"@id":"https:\/\/aachen-shopping.de\/nl\/2024\/06\/04\/volker-lang-accessoires\/"},"wordCount":514,"image":{"@id":"https:\/\/aachen-shopping.de\/nl\/2024\/06\/04\/volker-lang-accessoires\/#primaryimage"},"thumbnailUrl":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2024\/06\/EIA_VL.jpg","articleSection":["SHOPPEN-NIEUWS"],"inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/aachen-shopping.de\/nl\/2024\/06\/04\/volker-lang-accessoires\/","url":"https:\/\/aachen-shopping.de\/nl\/2024\/06\/04\/volker-lang-accessoires\/","name":"Volker Lang Accessoires - Einkaufen in Aachen","isPartOf":{"@id":"https:\/\/aachen-shopping.de\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aachen-shopping.de\/nl\/2024\/06\/04\/volker-lang-accessoires\/#primaryimage"},"image":{"@id":"https:\/\/aachen-shopping.de\/nl\/2024\/06\/04\/volker-lang-accessoires\/#primaryimage"},"thumbnailUrl":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2024\/06\/EIA_VL.jpg","datePublished":"2024-06-04T12:58:05+00:00","dateModified":"2024-06-13T11:46:51+00:00","author":{"@id":"https:\/\/aachen-shopping.de\/nl\/#\/schema\/person\/e7e4ecf5a1b2dcc107deec3ae378ee7e"},"description":"Volker Lang Aachen, Handtaschen, Ledermappen, Kulturtaschen, Schl\u00fcsselanh\u00e4nger, Necessaires, G\u00fcrtel, Fotom\u00e4ppchen in vielen Farben und Formen.","breadcrumb":{"@id":"https:\/\/aachen-shopping.de\/nl\/2024\/06\/04\/volker-lang-accessoires\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aachen-shopping.de\/nl\/2024\/06\/04\/volker-lang-accessoires\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/aachen-shopping.de\/nl\/2024\/06\/04\/volker-lang-accessoires\/#primaryimage","url":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2024\/06\/EIA_VL.jpg","contentUrl":"https:\/\/aachen-shopping.de\/wp-content\/uploads\/2024\/06\/EIA_VL.jpg","width":530,"height":617,"caption":"Volker Lang Einkaufen in Aachen"},{"@type":"BreadcrumbList","@id":"https:\/\/aachen-shopping.de\/nl\/2024\/06\/04\/volker-lang-accessoires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aachen-shopping.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Volker Lang Accessoires"}]},{"@type":"WebSite","@id":"https:\/\/aachen-shopping.de\/nl\/#website","url":"https:\/\/aachen-shopping.de\/nl\/","name":"Einkaufen in Aachen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aachen-shopping.de\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"https:\/\/aachen-shopping.de\/nl\/#\/schema\/person\/e7e4ecf5a1b2dcc107deec3ae378ee7e","name":"admin","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3599321e84ad68a7d8737390ec546368649423d41e0f49ba4af1a5b6151bb2a7?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/aachen-shopping.de\/nl\/author\/einkaufen-in-aachen\/"}]}},"_links":{"self":[{"href":"https:\/\/aachen-shopping.de\/nl\/wp-json\/wp\/v2\/posts\/33024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aachen-shopping.de\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aachen-shopping.de\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aachen-shopping.de\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aachen-shopping.de\/nl\/wp-json\/wp\/v2\/comments?post=33024"}],"version-history":[{"count":1,"href":"https:\/\/aachen-shopping.de\/nl\/wp-json\/wp\/v2\/posts\/33024\/revisions"}],"predecessor-version":[{"id":33060,"href":"https:\/\/aachen-shopping.de\/nl\/wp-json\/wp\/v2\/posts\/33024\/revisions\/33060"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aachen-shopping.de\/nl\/wp-json\/wp\/v2\/media\/32978"}],"wp:attachment":[{"href":"https:\/\/aachen-shopping.de\/nl\/wp-json\/wp\/v2\/media?parent=33024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aachen-shopping.de\/nl\/wp-json\/wp\/v2\/categories?post=33024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aachen-shopping.de\/nl\/wp-json\/wp\/v2\/tags?post=33024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}